{"id":29567,"date":"2014-01-20T15:08:32","date_gmt":"2014-01-20T14:08:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/poverta-il-comune-di-polistena-emette-gli-assegni-di-sopravvivenza\/"},"modified":"2023-01-17T12:46:03","modified_gmt":"2023-01-17T11:46:03","slug":"12385-poverta-il-comune-di-polistena-emette-gli-assegni-di-sopravvivenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12385-poverta-il-comune-di-polistena-emette-gli-assegni-di-sopravvivenza\/","title":{"rendered":"Povert\u00e0. Il Comune di Polistena emette gli assegni di &#8220;sopravvivenza&#8221;"},"content":{"rendered":"<p>POLISTENA (RC) &#8211; E&#8217; certamente un&#8217;idea unica nel suo genere e arriva dal Comune di Polistena.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L&#8217;amministrazione comunale del centro reggino infatti, in continuit\u00e0 con quanto avviato lo scorso anno, dar\u00e0 anche nel 2014 un sostegno economico ai giovani di nuclei familiari disoccupati, cio\u00e8 a coloro senza alcun reddito. L&#8217;idea dell&#8217;assegno di sopravvivenza ha riscontrato gi\u00e0 nel 2013 i primi risultati, intervenendo su circa 60 famiglie con un assegno mensile di 175 euro. L&#8217;iniziativa avr\u00e0 gli stessi criteri dello scorso anno. Nel 2013 infatti, l&#8217;assegno \u00e8 stato pari a 50 euro mensili ed \u00e8 stato &#8220;staccato&#8221; a favore dei giovani di senza lavoro dai 18 ai 29 anni. E anche per il 2014 il Comune di Polistena conceder\u00e0 un contributo per aiutare le famiglie di disoccupati che si trovano in situazioni di semipovert\u00e0 ad uscire dalla crisi che attanaglia il Paese. L&#8217;investimento per il 2014 \u00e8 di 120 mila euro. Tra le misure anticrisi gi\u00e0 adottate dall&#8217;Amministrazione Comunale di Polistena, oltre all&#8217;assegno di sopravvivenza, vi sono il mantenimento delle tariffe a parit\u00e0 di servizio e la definizione agevolata dei tributi comunali arretrati (depurati da sanzioni ed interessi) per i quali \u00e8 possibile presentare domanda entro il 28 febbraio. Come pure l&#8217;aumento del canone patrimoniale non ricognitorio rivolto non ai cittadini, ma ai colossi e gestori degli impianti a rete, che potrebbe costituire una fonte di entrata alternativa, per il finanziamento di servizi sociali e funzioni fondamentali del comune. Con l&#8217;assegno di sopravvivenza, l&#8217;Amministrazione Comunale pertanto ribadisce la necessit\u00e0, non pi\u00f9 procrastinabile, di introdurre nell&#8217;ordinamento italiano il reddito di cittadinanza, misura ormai presente in molti paesi europei, che il Governo tuttavia non intende assumere.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>POLISTENA (RC) &#8211; E&#8217; certamente un&#8217;idea unica nel suo genere e arriva dal Comune di Polistena.<\/p>\n","protected":false},"author":22,"featured_media":29568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29567"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29567\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29568"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}