{"id":296065,"date":"2026-06-22T13:30:21","date_gmt":"2026-06-22T11:30:21","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=296065"},"modified":"2026-06-22T13:31:29","modified_gmt":"2026-06-22T11:31:29","slug":"ospedale-cosenza-firme-comitato-spirito-santo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ospedale-cosenza-firme-comitato-spirito-santo\/","title":{"rendered":"Ospedale HUB a Cosenza, 2.859 firme per il referendum: aderisce anche il Comitato Piazza Spirito Santo"},"content":{"rendered":"<p>COSENZA &#8211; Il Comitato Spontaneo Piazza Spirito Santo aderisce alla raccolta firme promossa dall&#8217;Associazione 31 Ottobre per l&#8217;indizione del referendum consultivo sulla permanenza <a href=\"https:\/\/quicosenza.it\/news\/cosenza-piazza-ospedale-non-si-tocca-protesta\/\">dell&#8217;Ospedale HUB<\/a> nella citt\u00e0 di <strong>Cosenza<\/strong>. L&#8217;organismo civico ha accolto &#8220;con grande soddisfazione ed entusiasmo&#8221; la proposta finalizzata all&#8217;avvio della <strong>raccolta delle sottoscrizioni<\/strong> necessarie per consentire ai cittadini di esprimersi sul futuro del principale presidio ospedaliero dell&#8217;area.<\/p>\n<h3>Comitato aderisce alla raccolta firme: mantenere l&#8217;HUB a Cosenza<\/h3>\n<p>Il <a href=\"https:\/\/www.facebook.com\/comitatospiritosanto\" rel=\"noopener\"><strong>Comitato<\/strong> <\/a>chiarisce che la propria posizione <strong>non riguarda la scelta di una specifica localizzazione dell&#8217;ospedale<\/strong>, ma la <strong>tutela del ruolo sanitario, sociale e territoriale di Cosenza.<\/strong>\u00a0&#8220;La nostra battaglia non riguarda la scelta di un sito specifico, ma la difesa del ruolo sanitario, sociale e territoriale della citt\u00e0 di Cosenza. Per il Comitato \u00e8 fondamentale che l&#8217;Ospedale HUB continui a rimanere nel territorio comunale di Cosenza. Il luogo esatto in cui dovr\u00e0 essere realizzato \u00e8 una questione secondaria rispetto all&#8217;obiettivo principale: garantire che il principale presidio ospedaliero dell&#8217;area resti nella citt\u00e0 capoluogo&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293832\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Ospedale-di-Cosenza-protesta-comitati.jpg\" alt=\"Ospedale di Cosenza protesta comitati comitato\" width=\"653\" height=\"404\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Ospedale-di-Cosenza-protesta-comitati.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Ospedale-di-Cosenza-protesta-comitati-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Ospedale-di-Cosenza-protesta-comitati-768x475.jpg 768w\" sizes=\"auto, (max-width: 653px) 100vw, 653px\" \/><\/p>\n<h3>Polo universitario ad Arcavacata e Ospedale HUB: due progetti distinti<\/h3>\n<p>Il Comitato Piazza Spirito Santo esprime anche il proprio sostegno alla realizzazione di <strong>un polo clinico universitario ad Arcavacata<\/strong>, riconoscendone il valore strategico per il territorio:\u00a0&#8220;Siamo favorevoli\u00a0 riconoscendone l&#8217;importanza strategica per la formazione, la ricerca e l&#8217;innovazione sanitaria. Tuttavia, tale progetto non pu\u00f2 sostituire l&#8217;Ospedale HUB, che deve continuare a svolgere la propria funzione all&#8217;interno della citt\u00e0 di Cosenza&#8221;.<\/p>\n<p>Secondo il Comitato, i <strong>due interventi possono coesistere e rispondere a esigenze differenti<\/strong>: da un lato la formazione e la ricerca universitaria, dall&#8217;altro il mantenimento del principale presidio sanitario cittadino.<\/p>\n<h3>Obiettivo referendum: servono 2.859 firme<\/h3>\n<p>L&#8217;organizzazione annuncia un impegno diretto nella raccolta delle firme previste dall&#8217;articolo 14 dello Statuto Comunale, passaggio indispensabile per l&#8217;indizione del referendum in concomitanza con le elezioni comunali del 2027.<\/p>\n<p>&#8220;Per questo motivo il Comitato Spontaneo Piazza Spirito Santo sar\u00e0 fortemente impegnato nella raccolta delle firme previste dall&#8217;articolo 14 dello Statuto Comunale, necessarie per indire il <strong>referendum<\/strong> in concomitanza con le elezioni comunali del 2027. Saranno necessarie 2.859 firme e siamo pronti a dare il nostro contributo affinch\u00e9 questo importante strumento di partecipazione democratica possa essere attivato&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293834\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Caruso-manifestazione-ospedale-Cosenza.jpg\" alt=\"Caruso manifestazione ospedale Cosenza\" width=\"555\" height=\"346\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Caruso-manifestazione-ospedale-Cosenza.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Caruso-manifestazione-ospedale-Cosenza-300x187.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/Caruso-manifestazione-ospedale-Cosenza-768x479.jpg 768w\" sizes=\"auto, (max-width: 555px) 100vw, 555px\" \/><\/p>\n<h3>Il percorso avviato il 26 maggio<\/h3>\n<p>Il Comitato ricorda inoltre la partecipazione alla mobilitazione unitaria dello scorso <strong>26 maggio<\/strong>, promossa insieme all&#8217;Associazione 31 Ottobre, agli altri comitati di quartiere, a numerose associazioni cittadine e all&#8217;Amministrazione comunale.\u00a0L&#8217;iniziativa aveva l&#8217;obiettivo di difendere la permanenza dell&#8217;Ospedale HUB nella citt\u00e0 di Cosenza e ha rappresentato un momento di confronto e collaborazione tra realt\u00e0 civiche e istituzionali impegnate nella tutela del diritto alla salute e nel rafforzamento del ruolo di Cosenza come punto di riferimento sanitario dell&#8217;intero territorio.<\/p>\n<p>Per dare continuit\u00e0 al percorso gi\u00e0 avviato, il <strong>prossimo 25 giugno<\/strong> il Comitato Spontaneo Piazza Spirito Santo presenter\u00e0 al<a href=\"https:\/\/quicosenza.it\/news\/nuovo-ospedale-di-cosenza-comitati-di-quartiere\/\"> Coordinamento dei Comitati di Quartiere<\/a> la proposta di adesione alla raccolta firme.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comitato sostiene la consultazione popolare per difendere la permanenza del presidio sanitario nel capoluogo. Il 25 giugno la proposta sar\u00e0 portata al Coordinamento dei Comitati di Quartiere per costruire un fronte unitario cittadino<\/p>\n","protected":false},"author":42,"featured_media":292194,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-296065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=296065"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/292194"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=296065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=296065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=296065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}