{"id":296248,"date":"2026-06-24T16:08:35","date_gmt":"2026-06-24T14:08:35","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=296248"},"modified":"2026-06-24T16:08:35","modified_gmt":"2026-06-24T14:08:35","slug":"greco-la-calabria-puo-guidare-innovazion-nellia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/greco-la-calabria-puo-guidare-innovazion-nellia\/","title":{"rendered":"Rende. Greco: \u201cla Calabria ha tutte le carte in regola per guidare l\u2019innovazione nell\u2019IA\u201d"},"content":{"rendered":"<p>RENDE \u2013 \u201cOltre a rappresentare una <strong>grande soddisfazione personale<\/strong>, questo risultato \u00e8 un motivo di orgoglio per l\u2019intero sistema della ricerca e della formazione universitaria dell\u2019<strong><a href=\"https:\/\/quicosenza.it\/news\/intelligenza-artificiale-rettore-unical-governo\/\">Universit\u00e0<\/a> della Calabria<\/strong>\u201d. Ad affermarlo \u00e8 il r<strong>ettore dell\u2019UniCa<\/strong>l, <strong>Gianluigi Greco a QuiCosenza<\/strong> in merito alla nomina di qualche giorno fa che sar\u00e0 chiamato a coordinare il comitato di esperti che dovr\u00e0 supportare il sottosegretario alla <a href=\"https:\/\/www.governo.it\/it\" rel=\"noopener\">Presidenza<\/a> del Consiglio, <strong>Alessio Butti<\/strong>, nell&#8217;aggiornamento della Strategia nazionale per l&#8217;intelligenza artificiale 2026-2028.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-296252 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/IA-IMMAGINE.png\" alt=\"Rende. Greco: \u201cla Calabria ha tutte le carte in regola per guidare l\u2019innovazione nell\u2019IA\u201d\" width=\"465\" height=\"310\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/IA-IMMAGINE.png 1536w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/IA-IMMAGINE-300x200.png 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/IA-IMMAGINE-1024x683.png 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/IA-IMMAGINE-768x512.png 768w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/><\/p>\n<h3>Greco: &#8220;l&#8217;Italia deve essere protagonista attiva nello sviluppo e nell\u2019innovazione&#8221;<\/h3>\n<p>\u201cAvere la possibilit\u00e0 \u2013 prosegue sempre Greco &#8211; di avere <strong>un ruolo chiav<\/strong>e, decisivo, nella definizione della strategia italiana per l&#8217;<strong>intelligenza artificiale<\/strong>, \u00e8 di certo una responsabilit\u00e0, che porteremo avanti con convinzione e con grande dedizione\u201d. \u00a0Per il rettore dell\u2019Universit\u00e0 della Calabria, \u00e8 fondamentale che l\u2019Italia, in questo momento storico, inizi a definire una propria strategia, che non la veda pi\u00f9 soltanto come utilizzatrice di queste tecnologie, ma come protagonista attiva nello sviluppo e nell\u2019innovazione, all\u2019interno di uno scenario sempre pi\u00f9 globale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-296253 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/GRECO-1.jpg\" alt=\"Rende. Greco: \u201cla Calabria ha tutte le carte in regola per guidare l\u2019innovazione nell\u2019IA\u201d\" width=\"456\" height=\"256\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/GRECO-1.jpg 1414w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/GRECO-1-300x168.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/GRECO-1-1024x574.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/GRECO-1-768x431.jpg 768w\" sizes=\"auto, (max-width: 456px) 100vw, 456px\" \/><\/p>\n<p>Ed un ruolo importante potrebbero svolgerlo <strong>la Calabria e l&#8217;Universit\u00e0 della Calabria<\/strong> che sono gi\u00e0 un hub di riferimento, \u201caltrimenti \u2013 sottolinea il rettore Greco &#8211; questi successi e questa visibilit\u00e0 non sarebbero stati possibili. Abbiamo una struttura storica che si occupa di informatica, che si occupa di intelligenza artificiale, siamo assolutamente riconosciuti, c&#8217;\u00e8 una grande massa critica. Tutto questo permette di portare avanti dei progetti che hanno un grande respiro e un grande valore sul territorio. Ecco, &#8211; conclude sempre Greco- \u00a0<strong>la Calabria deve invertire un po&#8217; questa narrazione<\/strong>, deve iniziare a comprendere che ha davvero tutte le carte in regola per giocare un futuro da protagonista nei prossimi anni in Italia\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per Greco l\u2019Italia deve passare da semplice utilizzatrice a protagonista dello sviluppo dell\u2019intelligenza artificiale in uno scenario globale<\/p>\n","protected":false},"author":66,"featured_media":296255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-296248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=296248"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/296255"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=296248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=296248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=296248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}