{"id":296330,"date":"2026-06-25T12:55:57","date_gmt":"2026-06-25T10:55:57","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=296330"},"modified":"2026-06-25T13:09:04","modified_gmt":"2026-06-25T11:09:04","slug":"carenza-idrica-cosenza-donnici-verifiche-rete","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/carenza-idrica-cosenza-donnici-verifiche-rete\/","title":{"rendered":"Carenza idrica a Cosenza, i residenti di Donnici: \u00abS\u00ec ai controlli, ma verifiche anche sulla rete\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Di <a href=\"https:\/\/quicosenza.it\/news\/cosenza-carenza-idrica-donnici-controlli\/\" target=\"_blank\" rel=\"noopener\">carenza idrica e disagi a Donnici<\/a> aveva parlato nelle scorse ore il Comune di Cosenza, avvisando i cittadini che sarebbero scattati dei <strong>controlli stringenti<\/strong> su tutto il territorio interessato per verificare i consumi anomali riscontrati dalle verifiche fatte. Una scelta, quella dell&#8217;amministrazione, che i residenti accolgono con favore come fanno sapere tramite il<strong>\u00a0Comitato Tutela e Valorizzazione dell&#8217;Area Collinare a Sud di Cosenza<\/strong> ma che richiede per\u00f2, dicono, una riflessione pi\u00f9 ampia.<\/p>\n<h3>Residenti di Donnici su carenza idrica &#8220;non abbiamo nulla da nascondere&#8221;<\/h3>\n<p>Per i residenti \u00e8 necessario precisare &#8220;che il <strong>problema non riguarda esclusivamente le contrade citate<\/strong>, ma interessa un<strong> territorio molto pi\u00f9 ampio,<\/strong> comprendente numerose<strong> localit\u00e0 collinari e l&#8217;intero asse di Via Giovanni Macchione<\/strong> con le relative traverse&#8221;. Sui controlli, poi, i cittadini invitano il sindaco, gli assessori competenti e le forze dell&#8217;ordine &#8220;ad estendere le verifiche a tutto il territorio interessato. Non abbiamo nulla da nascondere &#8211; precisano &#8211; e garantiremo la massima collaborazione e trasparenza&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-272903\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rubinetto-acqua-1.jpg\" alt=\"Acqua cosenza erogazione carenza idrica \" width=\"395\" height=\"260\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rubinetto-acqua-1.jpg 718w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/10\/Rubinetto-acqua-1-300x198.jpg 300w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/p>\n<p>Per i residenti &#8220;le verifiche non possano riguardare esclusivamente gli utenti.<strong> \u00c8 doveroso accertare con la stessa attenzione anche le condizioni della rete idrica e le eventuali criticit\u00e0 gestionali<\/strong> che negli anni hanno contribuito ad aggravare il problema&#8221; chiedendo &#8220;<strong>chiarezza sullo stato della nuova rete idrica<\/strong> realizzata dalle precedenti amministrazioni, che secondo quanto riferito da numerosi cittadini non sarebbe mai entrata pienamente in funzione, continuando a gravare sulla vecchia condotta&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-82241\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carenza-idrica-a-Cetraro-1.png\" alt=\"carenza idrica donnici \" width=\"520\" height=\"247\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carenza-idrica-a-Cetraro-1.png 932w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carenza-idrica-a-Cetraro-1-300x143.png 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/carenza-idrica-a-Cetraro-1-768x365.png 768w\" sizes=\"auto, (max-width: 520px) 100vw, 520px\" \/><\/p>\n<p>Allo stesso modo, fanno presente i cittadini tramite il Comitato &#8220;<strong>non possono essere ignorate le <a href=\"https:\/\/quicosenza.it\/news\/perdite-idriche-a-donnici-inferiore-e-verzano\/\">numerose perdite idriche<\/a><\/strong> presenti sul territorio, spesso <a href=\"https:\/\/www.facebook.com\/comunedicosenzacs\/?locale=it_IT\" rel=\"noopener\">segnalate dai cittadini<\/a> e rimaste irrisolte per lunghi periodi, n\u00e9 gli sprechi derivanti dai tempi talvolta eccessivamente lunghi necessari per alcune riparazioni&#8221;.\u00a0I cittadini delle contrade, fa sapere il Comitato, &#8220;meritano rispetto e non possono essere associati, neppure indirettamente, alle cause di una <strong>problematica che richiede un&#8217;analisi pi\u00f9 ampia<\/strong>. La stragrande maggioranza delle <strong>famiglie utilizza l&#8217;acqua con responsabilit\u00e0 e nel pieno rispetto delle regole<\/strong>&#8220;.<\/p>\n<p>Per questo, i residenti chiedono &#8220;che ai controlli sui consumi si affianchino <strong>verifiche altrettanto rigorose sullo stato della rete<\/strong>, <strong>sulle perdite esistenti, sulle opere pubbliche<\/strong> realizzate e sulla loro effettiva funzionalit\u00e0. Le comunit\u00e0 delle contrade non cercano polemiche, ma risposte concrete. &#8211; aggiungono &#8211; L&#8217;obiettivo deve essere quello di individuare le reali cause dei disservizi e garantire finalmente un servizio efficiente ai cittadini, tutelando al tempo stesso la dignit\u00e0 e la correttezza di chi vive quotidianamente questi territori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I cittadini chiedono al Comune che ai controlli sui consumi si affianchino anche verifiche altrettanto rigorose sullo stato della rete, sulle perdite esistenti e sulle opere pubbliche realizzate <\/p>\n","protected":false},"author":90,"featured_media":179925,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-296330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=296330"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296330\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/179925"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=296330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=296330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=296330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}