{"id":296415,"date":"2026-06-25T19:48:57","date_gmt":"2026-06-25T17:48:57","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=296415"},"modified":"2026-06-25T19:48:57","modified_gmt":"2026-06-25T17:48:57","slug":"centri-estivi-bianca-rende-cosenza-famiglie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/centri-estivi-bianca-rende-cosenza-famiglie\/","title":{"rendered":"Centri estivi inclusivi, l\u2019affondo di Bianca Rende: \u201cA Cosenza famiglie lasciate sole\u201d"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Apprendiamo con interesse dell\u2019iniziativa promossa dal <strong>Comune di Rende a sostegno dei <a href=\"https:\/\/quicosenza.it\/news\/rende-centri-estivi-inclusiv-voucher-disabilita\/\" target=\"_blank\" rel=\"noopener\">centri estivi inclusivi<\/a><\/strong>, con risorse dedicate e contributi specifici per garantire assistenza educativa e partecipazione, a seguito di una puntuale analisi dei bisogni&#8221;. Lo dichiara in una nota la <strong>consigliera comunale di Cosenza, <a href=\"https:\/\/www.comune.cosenza.it\/it\/persone\/biancamaria-rende\" target=\"_blank\" rel=\"noopener\">Bianca Rende<\/a>.<\/strong><\/p>\n<p>&#8220;Una scelta importante che dimostra come, quando c\u2019\u00e8 volont\u00e0 politica, sia possibile dare risposte concrete alle famiglie. A Cosenza, invece, &#8211; prosegue Rende &#8211; <strong>continuiamo a registrare un grave ritardo<\/strong> su un tema che da anni portiamo all\u2019attenzione delle istituzioni. Da tempo chiediamo l\u2019attivazione di un servizio strutturato di sostegno ai centri estivi inclusivi, a partire dalle Ludoteche comunali, capace di garantire pari opportunit\u00e0 ai bambini e supporto reale alle loro famiglie durante i mesi estivi&#8221;.<\/p>\n<h3>Rende: &#8220;Chiediamo un modello stabile di sostegno ai centri estivi inclusivi&#8221;<\/h3>\n<p><strong>Purtroppo, anche quest\u2019anno, molte famiglie si trovano da sole ad affrontare costi insostenibili o, peggio ancora,<\/strong> a rinunciare completamente alla partecipazione dei propri figli alle attivit\u00e0 estive.<\/p>\n<p>Eppure i centri estivi non rappresentano un semplice momento ricreativo. Per tanti bambini sono occasioni fondamentali di socializzazione, crescita, autonomia, sport e partecipazione. Negare o limitare queste opportunit\u00e0 significa alimentare isolamento ed esclusione sociale. <strong>Non \u00e8 pi\u00f9 accettabile che l\u2019inclusione resti affidata esclusivamente al sacrificio delle famiglie o alla buona volont\u00e0 delle associazioni.<\/strong> Servono programmazione, investimenti competenze e servizi adeguati.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-296037 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/Autismo-ANGSA-Cosenza-centri-estivi.jpg\" alt=\"Autismo ANGSA Cosenza centri estivi\" width=\"508\" height=\"314\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/Autismo-ANGSA-Cosenza-centri-estivi.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/Autismo-ANGSA-Cosenza-centri-estivi-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/06\/Autismo-ANGSA-Cosenza-centri-estivi-768x475.jpg 768w\" sizes=\"auto, (max-width: 508px) 100vw, 508px\" \/><\/p>\n<p>Per questo<strong> chiediamo all\u2019Amministrazione comunale di Cosenza di attivarsi immediatamente<\/strong> <strong>per costruire un modello stabile di sostegno ai centri estivi inclusivi<\/strong>, coinvolgendo famiglie, scuole, associazioni e operatori del territorio. Chiediamo, ad esempio, di aprire le Ludoteche comunali per come previsto gi\u00e0 da tempo in bilancio e non ancora realizzato. Pare manchi la consegna dei locali al settore Educazione. Se cos\u00ec fosse, dopo due anni, sarebbe davvero scandaloso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293756 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1.jpg\" alt=\"centri estivi bambini disabilit\u00e0 Rende\" width=\"521\" height=\"322\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1-768x475.jpg 768w\" sizes=\"auto, (max-width: 521px) 100vw, 521px\" \/><\/p>\n<p>Le famiglie non possono pi\u00f9 aspettare. L\u2019inclusione non pu\u00f2 andare in vacanza. <strong>L&#8217;allarme lanciato da<a href=\"https:\/\/quicosenza.it\/news\/autismo-bambini-angsa-cosenza-estate-inclusiva\/\" target=\"_blank\" rel=\"noopener\"> ANGSA Cosenza<\/a><\/strong> sulle difficolt\u00e0 di accesso ai centri estivi per bambini e ragazzi con disturbo dello spettro autistico richiama l&#8217;attenzione sul diritto all&#8217;inclusione che non pu\u00f2 restare solo un principio formale. L<strong>&#8216;esclusione, anche indiretta, dei bambini pi\u00f9 fragili rappresenta una sconfitta per l\u2019intera societ\u00e0<\/strong> che non si pu\u00f2 accettare, alimentando anche le esternazioni di qualche neo leader nazionale di destra che fa delle divisioni un proprio mantra&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La consigliera comunale Bianca Rende denuncia i ritardi del Comune di Cosenza nel garantire servizi di supporto ai centri estivi inclusivi e chiede interventi immediati a favore delle famiglie<\/p>\n","protected":false},"author":58,"featured_media":296416,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[],"class_list":["post-296415","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=296415"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/296416"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=296415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=296415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=296415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}