{"id":296571,"date":"2026-06-27T18:40:22","date_gmt":"2026-06-27T16:40:22","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=296571"},"modified":"2026-06-27T18:41:55","modified_gmt":"2026-06-27T16:41:55","slug":"centri-estivi-inclus-ragazzi-disabilita-fondi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/centri-estivi-inclus-ragazzi-disabilita-fondi\/","title":{"rendered":"Centri estivi ed inclusione per i ragazzi con disabilit\u00e0, dalla Regione Calabria 1,8 milioni con &#8220;La mia estate&#8221;"},"content":{"rendered":"<p>CATANZARO &#8211; Abbandonare il congelamento relazionale che colpisce i ragazzi pi\u00f9 fragili alla chiusura delle scuole e restituire alle loro famiglie spazi di meritato <strong>sollievo, libert\u00e0 e tempo per s\u00e9<\/strong>. Con questo spirito la Regione Calabria vara <strong>\u201cLa mia estate\u201d<\/strong>, una misura strutturale promossa dal Dipartimento Welfare per facilitare l&#8217;accesso ai<a href=\"https:\/\/quicosenza.it\/news\/centri-estivi-famiglia-prezzi-folli-rinunce\/\" target=\"_blank\" rel=\"noopener\"> centri estivi <\/a>dei <strong>ragazzi con disabilit\u00e0,<\/strong> che mette in campo una <strong>dotazione finanziaria imponente da un milione e 800mila euro.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293756\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1.jpg\" alt=\"centri estivi bambini disabilit\u00e0 Rende\" width=\"503\" height=\"311\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/05\/centri-estivi-bambini-disabilita-1-768x475.jpg 768w\" sizes=\"auto, (max-width: 503px) 100vw, 503px\" \/><\/p>\n<h3>Sostegno per i centri estivi e per i ragazzi con disabilit\u00e0, voucher fino a 3mila euro<\/h3>\n<p>L\u2019intervento si traduce nell\u2019erogazione di <strong>voucher sociali fino a un massimo di 3.000 euro<\/strong> per ciascun beneficiario, destinati a sostenere l\u2019inclusione, le attivit\u00e0 ludiche e l\u2019assistenza alla socializzazione dei minori calabresi con disabilit\u00e0 certificata nel delicato periodo estivo. \u201cGarantire la felicit\u00e0, lo svago e l\u2019interazione dei nostri ragazzi non \u00e8 un lusso, ma un diritto sancito dalla Convenzione Onu e dalla legge 104 che la Calabria applica con i fatti \u2013 ha dichiarato l\u2019assessore al Welfare, Inclusione sociale e Pari opportunit\u00e0, <a href=\"https:\/\/www.regione.calabria.it\/la-regione\/la-giunta-regionale\/assessore-pasqualina-straface\/\" target=\"_blank\" rel=\"noopener\"><strong>Pasqualina Straface<\/strong><\/a> -. Insieme al presidente Occhiuto abbiamo ideato questo intervento guardando negli occhi le famiglie. Sappiamo che l\u2019estate, con la sospensione delle lezioni e delle terapie ordinarie, rischia di trasformarsi in un deserto di solitudine e in un carico assistenziale insostenibile per i genitori&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-289928\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/pasqualina-straface-regione-sostegni.jpg\" alt=\"Casali del Manco: convegno su disabilit\u00e0 e inclusione. Il progetto di vita personalizzato\" width=\"500\" height=\"309\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/pasqualina-straface-regione-sostegni.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/pasqualina-straface-regione-sostegni-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/04\/pasqualina-straface-regione-sostegni-768x475.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Con &#8220;La mia estate&#8221; secondo l&#8217;assessore, la Regione Calabria punta ad offrire &#8220;<strong>risposte tangibili:<\/strong> finanziamo la <strong>partecipazione a centri estivi, ludoteche, associazioni sportive e culturali,<\/strong> dando persino la possibilit\u00e0 di contrattualizzare direttamente un educatore professionale. Vogliamo che i ragazzi vivano esperienze di successo insieme ai loro coetanei e che i loro genitori possano ritagliarsi spazi di sollievo, sapendo che i propri figli sono inseriti in percorsi sicuri e stimolanti. Il mio augurio pi\u00f9 grande, che \u00e8 poi l\u2019obiettivo profondo di questa misura, \u00e8 che grazie a questo sostegno tutte le famiglie calabresi che convivono quotidianamente con la disabilit\u00e0 possano trascorrere momenti sereni in vacanza, al ristorante, o ovunque desiderino, riappropriandosi del proprio tempo libero con la massima spensieratezza\u201d.<\/p>\n<h3>A chi si rivolge la misura<\/h3>\n<p>L\u2019intervento, che <strong>coprir\u00e0 le attivit\u00e0 per una durata di due mesi<\/strong>, si rivolge a tutti i <strong>bambini e ragazzi disabili con diagnosi certificata,<\/strong> residenti in Calabria e di <strong>et\u00e0 compresa tra gli 8 e i 17 anni compiuti.<\/strong> Le risorse complessive saranno ripartite tra i 32 Ambiti territoriali sociali (Ats) della regione, che opereranno come soggetti attuatori in stretta sinergia con le Aziende sanitarie provinciali, il Terzo Settore ed i nuclei familiari.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-281710\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/alunni-disabilita-02.jpg\" alt=\"alunni disabilit\u00e0 02\" width=\"500\" height=\"309\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/alunni-disabilita-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/alunni-disabilita-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/01\/alunni-disabilita-02-768x475.jpg 768w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>La grande novit\u00e0 del progetto risiede nella <strong>flessibilit\u00e0 e nella totale libert\u00e0 di scelta garantita alla famiglia<\/strong> tramite il sistema dei voucher. Le somme concesse, determinate tenendo conto prioritariamente dell\u2019intensit\u00e0 del bisogno di sostegno e delle condizioni di particolare fragilit\u00e0 del nucleo familiare, potranno essere spese per l\u2019accesso a servizi offerti da un\u2019ampia rete di operatori accreditati, tra cui Enti del Terzo settore iscritti al Runts, cooperative sociali, associazioni o liberi professionisti iscritti ai relativi ordini professionali. Le risorse assegnate agli Ambiti terranno conto anche dei costi necessari per garantire il trasporto dei ragazzi presso i luoghi di svolgimento delle attivit\u00e0, abbattendo ogni tipo di barriera logistica.<\/p>\n<h3>&#8220;Puntiamo a coprire un vuoto assistenziale&#8221;<\/h3>\n<p>Il piano punta a generare un forte impatto sulla societ\u00e0 civile attraverso metodologie basate sul <strong>peer-tutoring<\/strong> (l\u2019affiancamento tra pari) e sull\u2019<strong>cooperative learning<\/strong> (l\u2019apprendimento cooperativo), stimolando anche la partecipazione di minori a sviluppo tipico per superare ogni forma di pregiudizio o paura della diversit\u00e0. L\u2019assegnazione del voucher non sar\u00e0 un freddo automatismo amministrativo, ma risponder\u00e0 agli obiettivi personalizzati individuati nel Piano assistenziale individualizzato (Pai) predisposto dalle Unit\u00e0 di valutazione multidimensionale (Uvm) o dai servizi sociali competenti.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-276518\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pasqualina-Straface.jpg\" alt=\"&quot;Donne Libere&quot; Straface Centri Famiglia convenzioni\" width=\"497\" height=\"279\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pasqualina-Straface.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pasqualina-Straface-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2025\/11\/Pasqualina-Straface-768x432.jpg 768w\" sizes=\"auto, (max-width: 497px) 100vw, 497px\" \/><\/p>\n<p>\u201cCon questa misura andiamo a<strong> coprire un vuoto assistenziale<\/strong> che gravava interamente sulle spalle dei genitori e sulle loro economie \u2013 ha concluso l\u2019assessore Straface -. Abbattiamo l\u2019isolamento sociale e <strong>costruiamo una rete reale attorno alla fragilit\u00e0.<\/strong> Non ci limitiamo a finanziare singole ore di assistenza, ma costruiamo ponti tra scuola, famiglia e territorio. Permettere a un genitore di trascorrere una serata fuori o un momento di riposo, mentre il proprio figlio sperimenta autonomia e socializzazione in un contesto inclusivo, significa applicare un welfare umano, presente e vicino alla vita reale delle persone. La Calabria mette al centro il valore di ogni individuo, specialmente quando la scuola si ferma\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La misura mette in campo l&#8217;erogazione di voucher sociali fino a un massimo di 3.000 euro per l&#8217;accesso a centri estivi, ludoteche, associazioni sportive e culturali, per bambini e ragazzi disabili con diagnosi certificata <\/p>\n","protected":false},"author":90,"featured_media":293757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-296571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=296571"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296571\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/293757"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=296571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=296571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=296571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}