{"id":296927,"date":"2026-07-02T10:00:25","date_gmt":"2026-07-02T08:00:25","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=296927"},"modified":"2026-07-02T10:20:53","modified_gmt":"2026-07-02T08:20:53","slug":"accordoinps-agearegionecalabriacontrocaporalato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/accordoinps-agearegionecalabriacontrocaporalato\/","title":{"rendered":"Accordo tra INPS, AGEA e Regione Calabria: pi\u00f9 controlli contro il caporalato in agricoltura"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; Potenziare i controlli nel <a href=\"https:\/\/quicosenza.it\/news\/braccianti-amendolara-commissione-inchiesta-lav\/\">settore agricolo<\/a> e contrastare le irregolarit\u00e0. Sono questi gli obiettivi dell&#8217;accordo istituzionale tra<strong><a href=\"https:\/\/www.inps.it\/\" rel=\"noopener\"> INPS<\/a>, AGEA e Regione Calabria<\/strong>, presentato nella nuova sede operativa di <strong>Agecontrol S.p.A.<\/strong><\/p>\n<p>L&#8217;apertura della sede rappresenta molto pi\u00f9 di un semplice traguardo logistico: \u00e8 il simbolo di una sinergia sempre pi\u00f9 stretta tra AGEA, INPS, Ispettorato Nazionale del Lavoro e INAIL nella lotta al caporalato e per il rispetto della cosiddetta condizionalit\u00e0 sociale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-296930 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/ddddd.jpg\" alt=\"Accordo tra INPS, AGEA e Regione Calabria: pi\u00f9 controlli contro il caporalato in agricoltura\" width=\"629\" height=\"356\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/ddddd.jpg 1443w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/ddddd-300x170.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/ddddd-1024x580.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/ddddd-768x435.jpg 768w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/p>\n<p>Con la nuova governance, AGEA ha avviato un profondo processo di riorganizzazione, accelerando i <strong>pagamenti agli agricoltori<\/strong> e realizzando un sistema di intelligence che dialoga con la piattaforma europea. Uno strumento che consente di individuare c<strong>omportamenti anomali e monitorare il territorio attraverso controlli documentali.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-296933 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/vitale.jpg\" alt=\"\" width=\"632\" height=\"330\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/vitale.jpg 1474w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/vitale-300x157.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/vitale-1024x534.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/07\/vitale-768x401.jpg 768w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h3>Lotta al caporalato, AGEA rafforza i controlli con INPS e Regione Calabria<\/h3>\n<p>A questo si affianca il lavoro di Agecontrol, societ\u00e0 interamente partecipata da AGEA, che conta circa <strong>300 dipendenti, di cui 250 ispettori.<\/strong> Grazie alle recenti norme contro le frodi agroalimentari, gli ispettori hanno acquisito la qualifica di pubblici ufficiali e possono effettuare verifiche sul rispetto delle norme giuslavoristiche. In caso di irregolarit\u00e0, sono previste sanzioni nei confronti delle aziende agricole che non rispettano gli obblighi previsti.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nuova sinergia tra INPS, AGEA e Regione Calabria punta a garantire legalit\u00e0, trasparenza e tutela dei lavoratori nel comparto agricolo<\/p>\n","protected":false},"author":66,"featured_media":296929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-296927","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/66"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=296927"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/296927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/296929"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=296927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=296927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=296927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}