{"id":29698,"date":"2014-01-24T12:21:23","date_gmt":"2014-01-24T11:21:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/armi-chimiche-a-gioia-tauro-una-catena-umana-di-bambini-per-dire-no\/"},"modified":"2023-01-17T12:46:10","modified_gmt":"2023-01-17T11:46:10","slug":"12451-armi-chimiche-a-gioia-tauro-una-catena-umana-di-bambini-per-dire-no","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12451-armi-chimiche-a-gioia-tauro-una-catena-umana-di-bambini-per-dire-no\/","title":{"rendered":"Armi chimiche a Gioia Tauro, una catena umana di bambini per dire &#8220;No&#8221;"},"content":{"rendered":"<p>SAN FERDINANDO (RC) &#8211; Bambini e ragazzi, genitori e insegnanti, per dire &#8220;no&#8221; all&#8217;arrivo delle navi con le armi chimiche della Siria nel porto di Gioia Tauro.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Una vera e propria catena umana ha circondato il municipio di San Ferdinando (Rc) questa mattina, composta da bambini e ragazzi delle scuole elementari e medie della cittadina tirrenica insieme ai loro genitori e insegnanti. Il corteo, partito dal plesso che ospita le due scuole e che si trova a circa 300 metri dalle banchine del porto, ha sfilato per le vie della cittadina per terminare nella piazza dove ha sede il municipio. Qui ragazzi ed adulti si sono presi per mano formando una catena umana. &#8220;Siamo stanchi &#8211; \u00e8 stato il commento pi\u00f9 diffuso &#8211; di essere presi in considerazione solo per vicende che mettono a rischio la nostra vita&#8221;. &#8220;Siamo qui per dire no &#8211; ha detto una mamma &#8211; all&#8217;arrivo di un carico di cui, nonostante le rassicurazioni, qui nessuno ne conosce il contenuto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN FERDINANDO (RC) &#8211; Bambini e ragazzi, genitori e insegnanti, per dire &#8220;no&#8221; all&#8217;arrivo delle navi con le armi chimiche della Siria nel porto di Gioia Tauro.<\/p>\n","protected":false},"author":22,"featured_media":29699,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29698"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29699"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}