{"id":29726,"date":"2014-01-25T14:52:40","date_gmt":"2014-01-25T13:52:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/vandali-attaccano-istituto-pubblico-comprensivo-carducci-da-feltre\/"},"modified":"2023-01-17T12:46:12","modified_gmt":"2023-01-17T11:46:12","slug":"12468-vandali-attaccano-istituto-pubblico-comprensivo-carducci-da-feltre","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12468-vandali-attaccano-istituto-pubblico-comprensivo-carducci-da-feltre\/","title":{"rendered":"Vandali attaccano Istituto Pubblico Comprensivo Carducci- Da Feltre"},"content":{"rendered":"<p>REGGIO CALABRIA \u2013 L\u2019istituto pubblico comprensivo Carducci- Da Feltre subisce, da mesi, attacchi continui di vandali e ladri.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Molotov contro finestre e portone d\u2019ingresso, furti, incendi, scritte offensive contro lo Stato e le forze dell\u2019ordine. Forse qualcuno non vede di buon occhio il cammino tecnologico di questo istituto, &#8220;fiore all\u2019occhiello&#8221; della citt\u00e0. Il Carducci \u00e8, infatti, una scuola di alta formazione con metodi di studio all\u2019avanguardia che potrebbero aver indispettito o causato risentimenti divenuti, poi, attacchi violenti contro la struttura. La scuola \u00e8 frequentata da figli di esponenti di forze dell\u2019ordine e di magistrati.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">L&#8217;ultimo attentato risale alla scorsa notte. Gli &#8220;ignoti&#8221; hanno bruciato condizionatori e alcune finestre. Un&#8217;aggiunta a danni pregressi causati a giostre, aule, computer. I malviventi hanno, inoltre, imbrattato i muri della scuola con frasi ingiuriose contro Stato e forze dell\u2019ordine con la sigla A.C.A.B.(acronimo di All Cops Are Bastards) e \u00abFuck the Police\u00bb.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Lo scopo \u00e8 ben preciso: i bambini che frequentano il Carducci-Da Feltre hanno a disposizione, nonostante l\u2019et\u00e0, strutture d\u2019apprendimento di ultima generazione acquistate grazie al contributo dei fondi Pon (lavagne elettroniche, strumenti musicali e sala concerti) che proiettano le conoscenze su livelli di gran lunga superiori a quelli che forniscono le altre scuole private della citt\u00e0 dello Stretto. E questo a qualcuno potrebbe non andare gi\u00f9. La stessa dirigente scolastica, Rina Manganaro, avrebbe subito un furto nella sua abitazione. I ladri le hanno portato via gioielli e refurtiva per un valore di 200 mila euro.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Laddove il crimine organizzato la fa da padrone, \u00e8 facile ipotizzare che anche sull\u2019educazione scolastica ci possano essere ostacoli e obiezioni , soprattutto quando \u00e8 proprio la scuola a diventare un &#8220;business&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA \u2013 L\u2019istituto pubblico comprensivo Carducci- Da Feltre subisce, da mesi, attacchi continui di vandali e ladri.<\/p>\n","protected":false},"author":22,"featured_media":29727,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-29726","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29726"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29726\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29727"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}