{"id":29736,"date":"2014-01-26T15:37:18","date_gmt":"2014-01-26T14:37:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-cosenza-calcio-batte-la-vigor-lamezia-e-torna-in-testa-alla-classifica\/"},"modified":"2023-01-17T12:46:13","modified_gmt":"2023-01-17T11:46:13","slug":"12473-il-cosenza-calcio-batte-la-vigor-lamezia-e-torna-in-testa-alla-classifica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12473-il-cosenza-calcio-batte-la-vigor-lamezia-e-torna-in-testa-alla-classifica\/","title":{"rendered":"Il Cosenza Calcio batte la Vigor Lamezia e torna in testa alla classifica"},"content":{"rendered":"<p>COSENZA &#8211; Un Cosenza autoritario, torna alla vittoria nel derby contro la Vigor Lamezia ed approfitta della battuta d&#8217;arresto del Teramo, sconfitto dal Tuttocuoio, balzando al comando della classifica del Girone B della Lega Pro Seconda Divisione.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Gli uomini di mister <strong>Cappellacci<\/strong> hanno condotto una gara autoritaria, non lasciando alcun spazio di manovra ad una Vigor Lamezia apparsa veramente inconsistente. Nonostante i problemi a centrocampo, il tecnico dei <strong>silani<\/strong> ha schierato <strong>Guidi<\/strong> nell&#8217;inedito ruolo di <strong>playmake<\/strong>r davanti alla difesa, gettando nella mischia il nuovo acquisto <strong>Asante<\/strong> accanto a Criaco. In difesa schierati centrali Blondett e Pepe, con Bigoni e Mannini sugli esterni. In attacco la coppia De Angelis, autore di una doppietta, e Mosciaro. La Cronaca Pronti via ed il <strong>Cosenza<\/strong> passa subito in vantaggio con <strong>De Angelis<\/strong> che raccoglie sotto misura un cross dalla destra di Alessandro. al 17&#8242; Guidi di testa sfiora il raddoppio su azione d&#8217;angolo. al 32&#8242; si affaccia la <strong>Vigor<\/strong> dalle parti di <strong>Frattali<\/strong> con un tiro di Zampaglione che non impensierisce l&#8217;estremo difensore silano. Al 40&#8242; un cattivo controllo di Marchetti libera Alessandro solo davanti a <strong>Piacenti<\/strong>, ma il pallonetto dell&#8217;attaccante rossoblu non impensierisce il portiere della Vigor. Un minuto dopo \u00e8 <strong>De Angelis<\/strong> a sfuggire alla retroguardia lametina presentandosi a tu per tu con Piacenti e superandolo con un pallonetto che finisce sul fondo poco distante dalla porta dei <strong>biancoverdi<\/strong>. Subito dopo si accende un plateale <strong>diverbio<\/strong> tra i due attaccanti silani con <strong>Mosciaro<\/strong> che reclamava un passaggio per potere concludere a porta sguarnita. Dopo un minuto di recupero si va al riposo. Nel secondo tempo la Vigor si mostra pi\u00f9 intraprendente collezionando per\u00f2 solo una serie di calci d&#8217;angolo che non avranno esito. Al 61&#8242; <strong>De Angelis<\/strong> viene atterrato in area ma rimedia solo un cartellino giallo per simulazione che gli coster\u00e0 la <strong>squalifica<\/strong> nella prossima gara. Un minuto dopo per\u00f2 l&#8217;attaccante del Cosenza sfrutta al meglio un lancio in profondit\u00e0 di Asante siglando il <strong>raddoppio<\/strong> suo personale e della squadra. al 65&#8242; ancora una bella occasione per i silani sull&#8217;asse Asante &#8211; De Angelis con il tiro di quest&#8217;ultimo smorzato da Marchetti che salva il <strong>Lamezia<\/strong>. Inizia la girandola delle sostituzioni, ma la musica non cambia, il <strong>Cosenza<\/strong> gestisce la gara e concede poco alla Vigor che si rende pericolosa con uno dei nuovi entrati, <strong>Tozzi<\/strong>, che sfiora di testa la marcatura al minuto 81&#8242;, subito dopo avere costretto Pepe ad un fallo al limite dell&#8217;area, costato l&#8217;espulsione al difensore rossoblu. Nei minuti finali c&#8217;\u00e8 gloria anche per <strong>Calderini<\/strong>, subentrato ad uno spento Mosciaro, che sfrutta al meglio una ripartenza siglando la rete finale che fissa il punteggio su un <strong>rotondo<\/strong> ed ineccepibile 3 a 0.<\/p>\n<p>NOTE:<\/p>\n<p><strong>Cosenza<\/strong>: Frattali, Blondett, Mannini,Bigoni, Pepe,Guidi, Criaco, Asante (84&#8217;Carrieri), Mosciaro (68&#8242; Calderini), De Angelis, Alessandro(68&#8242; Palazzi). Allenatore : Cappellacci. In panchina : Orlandi, Adamo,Carrieri, Palazzi, Mannarino, Calderini, Chinellato.<\/p>\n<p><strong>V.Lamezia<\/strong>: Piacenti, Rapisarda, Malerba (55&#8242; Malerba), Romano (68&#8242; Tozzi), Marchetti, Gattari, Zampaglione, Giamp\u00e0, Del Sante, Meucci, D\u2019Amico (76&#8242; Mangiapane). Allenatore : Novelli. In panchina : Bibba, Gona, Strumbo, Scarsella, Rondinelli, Tozzi, Mangiapane.<\/p>\n<p><strong>Arbitro<\/strong>, Sig. Alessandro Greco (Lecce) I\u00b0 Ass. Luigi Lanotte (Barletta) II\u00b0 Ass. Salvatore Stasi (Barletta).<\/p>\n<p><strong>Angoli<\/strong> Cosenza: 1 Vigor Lamezia: 6<\/p>\n<p><strong>Ammoniti<\/strong>: 43&#8242; Mosciaro (C);51&#8242; Malerba (V), 54&#8242; Pepe (C), 61&#8242; De Angelis (C), 83&#8242; Tozzi (V). <strong>Espulso<\/strong>: 80\u00b0 Pepe (C) Recupero: 1&#8242; pt; 4&#8242; st.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Un Cosenza autoritario, torna alla vittoria nel derby contro la Vigor Lamezia ed approfitta della battuta d&#8217;arresto del Teramo, sconfitto dal Tuttocuoio, balzando al comando della classifica del Girone B della Lega Pro Seconda Divisione.<\/p>\n","protected":false},"author":22,"featured_media":29737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-29736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29736"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29736\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29737"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}