{"id":29740,"date":"2014-01-26T20:16:26","date_gmt":"2014-01-26T19:16:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-cosenza-torna-in-vetta-alla-classifica\/"},"modified":"2023-01-17T12:46:13","modified_gmt":"2023-01-17T11:46:13","slug":"12475-il-cosenza-torna-in-vetta-alla-classifica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12475-il-cosenza-torna-in-vetta-alla-classifica\/","title":{"rendered":"Il Cosenza torna in vetta alla classifica"},"content":{"rendered":"<p>COSENZA &#8211; Pronto riscatto del Cosenza, che dopo la brutta prova di Sorrento torna alla vittoria.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La squadra di <strong>Cappellacci<\/strong> vince e convince, fornendo una delle migliori prestazioni viste al <strong>San<\/strong> <strong>Vito<\/strong> in questo campionato. Partita scivolata via senza particolari problemi per la truppa <strong>rosso<\/strong> <strong>blu<\/strong>, che gi\u00e0 dai primi minuti di gioco \u00e8 parsa squadra fuori portata per i <strong>lametini<\/strong>. Partita mai in discussione, con i <strong>rosso<\/strong> <strong>blu<\/strong> che dal primo all&#8217;ultimo minuto di gioco hanno condotto la gara. <strong>Carattere<\/strong>, <strong>grinta<\/strong> e sopratutto voglia di <strong>vincere<\/strong>, queste sono state le caratteristiche che hanno fatto la differenza ed hanno permesso al <strong>Cosenza<\/strong> di vivere una domenica di assoluta tranquillit\u00e0. La squadra rosso blu \u00e8 parsa completamente trasformata rispetto alla brutta gara di <strong>Sorrento<\/strong>, dove francamente avevamo notato poca voglia di lottare e di soffrire. Alla vigilia non era facile pronosticare un risultato cos\u00ec rotondo, sopratutto per le difficolt\u00e0 di formazione, visto che il centrocampo rosso blu era nuovo di zecca e con giocatori che non avevano mai giocato assieme. Ma quest&#8217;anno il <strong>Cosenza<\/strong> \u00e8 pi\u00f9 forte di qualsiasi avversit\u00e0 dimostrando di essere un gruppo <strong>coeso<\/strong> e <strong>maturo<\/strong>. Merito di questo va ascritto ai giocatori in primis ed allenatore e staff dirigenziale poi. Tornando alla partita non possiamo che sottolineare come il risultato non sia stato mai in discussione, con il Cosenza parso pi\u00f9 squadra, al cospetto di una Vigor Lamezia francamente slegata e poco incisiva. \u00c8 stato un Cosenza diverso anche dal punto di vista tattico, meno possesso palla e pi\u00f9 giocate in verticale, con <strong>Alessandro<\/strong> tornato su livelli di assoluto valore, con <strong>De<\/strong> <strong>Angelis<\/strong> cecchino infallibile, se a questo aggiungiamo un <strong>Calderini<\/strong> che capitalizza al massimo i minuti in cui gioca il tutto si spiega. Sugli scudi anche la difesa, che nei pochi momenti in cui \u00e8 stata chiamata in causa ha risposto nel migliore dei modi. Per ultimo lasciamo il centrocampo, per il quale ci sar\u00e0 modo e tempo per migliorare, auspicando l&#8217;arrivo di qualche altro elemento. <strong>Cappellacci<\/strong> pu\u00f2 comunque essere contento dei suoi uomini, visto le risposte che hanno fornito in questa partita. Anche oggi si \u00e8 potuto notare come un giocatore come <strong>Guidi<\/strong> si \u00e8 adattato ad un ruolo non propriamente abituale, dimostrando che questo gruppo ha &nbsp;sposato in toto il volere del suo allenatore e l&#8217;attaccamento per questa gloriosa maglia. In conclusione ci piace rimarcare l&#8217;assoluta correttezza dei giocatori in campo e dei tifosi cosentini sugli spalti che ancora una volta hanno dimostrato di essere dei veri sportivi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Pronto riscatto del Cosenza, che dopo la brutta prova di Sorrento torna alla vittoria.<\/p>\n","protected":false},"author":22,"featured_media":29741,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-29740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29740"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29741"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}