{"id":297595,"date":"2026-07-10T09:20:01","date_gmt":"2026-07-10T07:20:01","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=297595"},"modified":"2026-07-10T09:20:44","modified_gmt":"2026-07-10T07:20:44","slug":"nove-furti-4-regioni-calabria-270mila-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/nove-furti-4-regioni-calabria-270mila-euro\/","title":{"rendered":"Nove furti in 4 regioni tra cui la Calabria: arrestato 42enne, un bottino da 270mila euro"},"content":{"rendered":"<p>TARANTO &#8211; E&#8217; stato arrestato perch\u00e8 ritenuto responsabile di una serie di furti aggravati commessi tra il <strong>2024 e il 2025 in Puglia, Campania, Basilicata e Calabria<\/strong>. I carabinieri della stazione di Avetrana, in provincia di Taranto, con il supporto dei militari della stazione di Bari Santo Spirito, hanno eseguito un&#8217;ordinanza di custodia cautelare agli <strong>arresti domiciliari con braccialetto elettronico<\/strong> nei confronti di un 42enne barese.<\/p>\n<p>Il provvedimento \u00e8 stato emesso dal gip del Tribunale di Taranto su richiesta della Procura e rappresenta l&#8217;esito di <strong>un&#8217;indagine avviata<\/strong> dopo il furto ai <strong>danni di un&#8217;azienda<\/strong> del <strong>settore alimentare di Avetrana, avvenuto il 18 giugno 2024.<\/strong><\/p>\n<h3>Le indagini sui numerosi furti<\/h3>\n<p>Le investigazioni hanno permesso di ricostruire gli spostamenti dell&#8217;indagato attraverso l&#8217;analisi delle immagini dei sistemi di videosorveglianza, dei <strong>tabulati telefonici<\/strong>, dei dati di traffico telematico, delle localizzazioni Gps e di numerosi riscontri effettuati sul territorio. Secondo gli inquirenti, il <strong>presunto autore dei colpi avrebbe agito seguendo un modus operandi ben definito<\/strong>, individuando preventivamente gli obiettivi commerciali e colpendoli prevalentemente nelle <strong>ore notturne<\/strong>.<\/p>\n<p>Nel corso dell&#8217;inchiesta sono stati ricostruiti <strong>nove episodi criminosi<\/strong>, messi a segno nell&#8217;arco di pochi mesi in quattro regioni del Mezzogiorno. Il valore complessivo del denaro e della merce sottratti <strong>ammonterebbe a circa 270mila euro<\/strong>, ai quali si aggiungono i rilevanti danni provocati alle attivit\u00e0 commerciali prese di mira.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ai domiciliari con braccialetto elettronico un uomo di Bari, accusato di una serie di furti aggravati commessi tra il 2024 e il 2025 in Puglia, Campania, Basilicata e Calabria. L&#8217;indagine \u00e8 partita da un colpo messo a segno ad Avetrana<\/p>\n","protected":false},"author":42,"featured_media":297596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-297595","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/297595","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=297595"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/297595\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/297596"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=297595"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=297595"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=297595"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}