{"id":29766,"date":"2014-01-27T10:49:03","date_gmt":"2014-01-27T09:49:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cosenza-vigor-lamezia-3-0-le-foto\/"},"modified":"2023-01-17T12:46:16","modified_gmt":"2023-01-17T11:46:16","slug":"12488-cosenza-vigor-lamezia-3-0-le-foto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12488-cosenza-vigor-lamezia-3-0-le-foto\/","title":{"rendered":"Cosenza-Vigor Lamezia 3-0, le foto"},"content":{"rendered":"<p>COSENZA &#8211; riviviiamo la bella vittoria del Cosenza nel derby contro la Vigor lamezia della scorsa giornata del campionato di Lega Pro seconda divisione Girone B, attraverso le splendide immagini di Ernesto pescatore e Riccardo Tucci.<\/p>\n<p>{imageshow sl=71 sc=3 \/}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; riviviiamo la bella vittoria del Cosenza nel derby contro la Vigor lamezia della scorsa giornata del campionato di Lega Pro seconda divisione Girone B, attraverso le splendide immagini di Ernesto pescatore e Riccardo Tucci. {imageshow sl=71 sc=3 \/}<\/p>\n","protected":false},"author":22,"featured_media":29767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-29766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=29766"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/29766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/29767"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=29766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=29766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=29766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}