{"id":297845,"date":"2026-07-13T21:00:05","date_gmt":"2026-07-13T19:00:05","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=297845"},"modified":"2026-07-14T06:49:08","modified_gmt":"2026-07-14T04:49:08","slug":"agricoltura-calabria-ristori-ciclone-harry","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/agricoltura-calabria-ristori-ciclone-harry\/","title":{"rendered":"Agricoltura in Calabria, al via i ristori economici per il ciclone Harry: domande entro il 25 luglio"},"content":{"rendered":"<p>CATANZARO &#8211; C&#8217;\u00e8 tempo fino al <strong>25 luglio 2026<\/strong> per consentire alle <strong>aziende agricole calabresi<\/strong> di presentare la<strong> domanda di ristoro<\/strong> per i gravissimi danni provocati dal <strong>ciclone Harry<\/strong>. La Regione Calabria ha infatti annunciato l&#8217;apertura ufficiale dei termini sulla piattaforma digitale dedicata, avviando la prima fase di un iter straordinario volto a<strong> sostenere il comparto agroalimentare<\/strong> dopo le eccezionali ondate di maltempo che hanno flagellato il territorio tra il 18 gennaio e la fine di febbraio del 2026.<\/p>\n<p>I fondi arrivano direttamente da uno <a href=\"https:\/\/quicosenza.it\/news\/governo-danni-ciclone-harry-calabria\/\" target=\"_blank\" rel=\"noopener\">stanziamento speciale<\/a> del Ministero dell&#8217;Agricoltura, della Sovranit\u00e0 Alimentare e delle Foreste, che ha messo sul piatto un <strong>plafond complessivo di 112 milioni di euro<\/strong> da ripartire tra le tre regioni pi\u00f9 colpite: Calabria, Sicilia e Sardegna.<\/p>\n<h3><strong>Ciclone Harry: chi pu\u00f2 fare domanda, requisiti e territori inclusi<\/strong><\/h3>\n<p>La misura, gestita in questa fase iniziale per via telematica, \u00e8 rivolta esclusivamente al ripristino delle <strong>strutture aziendali<\/strong> danneggiate. Possono accedere ai contributi le imprese che rispondono a precisi requisiti:<\/p>\n<ul>\n<li><strong>Attivit\u00e0:<\/strong> Imprese agricole attive nella produzione primaria.<\/li>\n<li><strong>Inquadramento:<\/strong> Iscritte alla Camera di Commercio e titolari di un fascicolo aziendale aggiornato.<\/li>\n<li><strong>Localizzazione:<\/strong> Le strutture devono ricadere all&#8217;interno delle aree delimitate e geolocalizzate dalla delibera della Giunta regionale n. 208 del 28 aprile 2026 e dal successivo decreto ministeriale del 27 maggio 2026.<\/li>\n<\/ul>\n<p><strong>Come funziona la procedura in due step:<\/strong> In questi primi giorni (fino al 25 luglio) sul portale <a href=\"https:\/\/www.sian.it\/portale-opagea\/home.jsp\" target=\"_blank\" rel=\"noopener\">Agea\/Sian<\/a> verr\u00e0 acquisita l&#8217;anagrafica del richiedente e dell&#8217;azienda. Successivamente, i beneficiari dovranno trasmettere la documentazione tecnica integrativa e le perizie tramite uno specifico applicativo che verr\u00e0 attivato sempre sul sistema Sian.<\/p>\n<h3>Modello Calabria: digitalizzazione e indennizzi &#8220;de minimis&#8221;<\/h3>\n<p>L&#8217;intero impianto burocratico \u00e8 stato snellito per garantire pagamenti rapidi ed evitare le lungaggini del passato. La Calabria ha giocato un ruolo di primo piano nello sviluppo della nuova piattaforma, collaborando attivamente con l&#8217;Agenzia per le erogazioni in agricoltura.\u00a0<em>&#8220;La Calabria \u00e8 stata tra le regioni che hanno maggiormente contribuito alla sperimentazione e allo sviluppo della piattaforma digitale&#8221;<\/em> \u2013 fa sapere la Regione \u2013 <em>&#8220;oggi fondamentale per velocizzare le procedure istruttorie e l&#8217;erogazione dei contributi&#8221;<\/em>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-286624 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/agricoltura-CIA.jpg\" alt=\"agricoltura - CIA\" width=\"663\" height=\"410\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/agricoltura-CIA.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/agricoltura-CIA-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2026\/03\/agricoltura-CIA-768x475.jpg 768w\" sizes=\"auto, (max-width: 663px) 100vw, 663px\" \/><\/p>\n<h2>In arrivo un secondo bando per le produzioni agricole<\/h2>\n<p>L&#8217;intervento attuale rappresenta solo la prima parte degli aiuti programmati. L&#8217;Assessore regionale all&#8217;Agricoltura, <strong>Gianluca Gallo<\/strong>, ha confermato che la macchina organizzativa \u00e8 gi\u00e0 al lavoro per ristorare anche la perdita dei raccolti e delle produzioni del 2026. \u201c<em>Non era affatto scontato ottenere questo importante sostegno da parte del Ministero<\/em> &#8211; ha dichiarato l\u2019assessore regionale. <em>Si tratta di <strong>risorse che si aggiungono agli interventi gi\u00e0 messi in campo dalla Protezione civile e<\/strong> che sono rivolte in modo specifico alle aziende agricole duramente colpite dagli eventi meteorologici eccezionali&#8221;. <\/em><\/p>\n<p><em>&#8220;Dopo questo avviso seguir\u00e0 a br<strong>eve un ulteriore bando dedicato ai danni subiti dalle produzioni agricole.<\/strong> Rivolgo un invito a tutte le imprese interessate a presentare la domanda entro il termine del 25 luglio, cos\u00ec da consentire il riconoscimento dei ristori spettanti e sostenere concretamente la ripresa delle attivit\u00e0 produttive<\/em>\u201d.<\/p>\n<p><strong>1.Fase 1: Danni Strutturali (In corso): <\/strong>Scadenza 25 luglio 2026<\/p>\n<p>Raccolta delle domande sul portale Agea\/Sian per i danni a stalle, magazzini, serre e impianti strutturali legati al ciclone Harry.<\/p>\n<p><strong>2.Fase 2: Integrazione Documentale: <\/strong>Prossimamente<\/p>\n<p>Inserimento online delle perizie tecniche e della documentazione di dettaglio sul sistema informatico Sian<\/p>\n<p><strong>3.Fase 3: Ristori alle Produzioni: <\/strong>In via di emanazione<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Attiva la procedura per i danni strutturali causati dalla violenta ondata di maltempo di inizio 2026. L&#8217;assessore Gianluca Gallo: &#8220;Risorse straordinarie dal Ministero. A breve un secondo bando per la perdita delle produzioni&#8221;<\/p>\n","protected":false},"author":55,"featured_media":297847,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-297845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/297845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=297845"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/297845\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/297847"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=297845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=297845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=297845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}