{"id":297983,"date":"2026-07-14T20:50:08","date_gmt":"2026-07-14T18:50:08","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=297983"},"modified":"2026-07-14T20:50:08","modified_gmt":"2026-07-14T18:50:08","slug":"cosenza-pres-collegio-revisori-conti-caldiero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-pres-collegio-revisori-conti-caldiero\/","title":{"rendered":"Cosenza, il Consiglio comunale nomina il nuovo Presidente del collegio dei revisori dei conti: \u00e8 Fernando Caldiero"},"content":{"rendered":"<p>COSENZA &#8211; Il Consiglio comunale, presieduto da Giuseppe Mazzuca, ha nominato, nella seduta di oggi pomeriggio, il <strong>nuovo Presidente del collegio dei Revisori dei conti.<\/strong> Si tratta del dottor <strong>Fernando Caldiero, <\/strong>nominativo che si aggiunge agli altri due componenti dell&#8217;organo di revisione risultati dal sorteggio effettuato precedentemente e trasmesso al Comune dalla Prefettura.<\/p>\n<h3>Cosenza, completato il collegio dei Revisori dei conti<\/h3>\n<p>Il primo revisore estratto \u00e8<strong> Antonio Pilello,<\/strong> il secondo <strong>Marcello Scarpelli.<\/strong> La nomina del dottor Caldiero a Presidente del collegio dei revisori dei conti del Comune di Cosenza \u00e8 avvenuta a seguito della votazione del Consiglio comunale. Si \u00e8 proceduto per appello nominale ed ogni consigliere ha deposto la propria scheda nell&#8217;urna appositamente collocata nell&#8217;aula consiliare.<\/p>\n<p>Ha votato anche il <a href=\"https:\/\/www.facebook.com\/franzcaruso\" target=\"_blank\" rel=\"noopener\"><strong>sindaco Franz Caruso<\/strong><\/a> al termine delle operazioni di voto dei consiglieri comunali. Il Presidente Mazzuca, prima di iniziare le operazioni di voto, aveva nominato come scrutatori i consiglieri comunali Giuseppe Ciacco e Giuseppe d&#8217;Ippolito. Al termine della votazione, \u00e8 risultato eletto il dottor Fernando Caldiero che ha riportato 20 voti. 5 sono state le schede bianche. Un solo voto \u00e8 stato riportato da Angelo Brutto ed un voto anche da Maria Patrizia Florio.<\/p>\n<h3>Gli altri punti all&#8217;ordine del giorno: realizzazione di fabbricati<\/h3>\n<p>Nel corso del Consiglio comunale del Comune di Cosenza si \u00e8 poi passati alla trattazione degli altri punti all&#8217;ordine del giorno, anzitutto<strong> l&#8217;approvazione dello schema di convenzione<\/strong> relativo alla <strong>realizzazione di un fabbricato residenziale multipiano<\/strong> in un&#8217;area ricadente in Zona territoriale omogenea B5, a margine delle sedi stradali di <strong>via Paolo Borsellino e via Rocco Chinnici<\/strong>, in variante al permesso da costruire gi\u00e0 rilasciato precedentemente.<\/p>\n<p>Sul punto ha relazionato il dirigente del Settore Urbanistica del Comune di Cosenza, Francesco Azzato. &#8220;Si tratta \u2013 ha spiegato &#8211; della riapprovazione della convenzione ai sensi dell&#8217;art.28 bis del D.P.R. 6 giugno 2001, n.380, nel caso in cui si voglia attuare un intervento con realizzazione semplificata degli oneri di urbanizzazione. Questo intervento \u2013 ha aggiunto il dirigente Azzato \u2013 era gi\u00e0 stato approvato l&#8217;anno scorso e riguarda la realizzazione di un <strong>edificio di edilizia residenziale<\/strong>. La riapprovazione della convenzione \u00e8 dovuta al fatto che, a seguito dell&#8217;acquisizione di ulteriori aree, \u00e8 emersa la possibilit\u00e0 per il proponente di realizzare un volume aggiuntivo rispetto a quello gi\u00e0 convenzionato precedentemente. Poich\u00e9 tutto questo comporta una variante essenziale dei termini della convenzione, si rende necessario riapprovarla. La variante riguarda soltanto un incremento volumetrico per la chiusura di alcuni spazi che precedentemente erano stati lasciati aperti&#8221;.<\/p>\n<p>Sul punto non si sono registrati interventi da parte dei consiglieri comunali, neanche in sede di dichiarazioni di voto. Posta in votazione, la <strong>pratica \u00e8 passata all&#8217;unanimit\u00e0.<\/strong><\/p>\n<p>Anche il punto successivo, riguardante sempre l&#8217;approvazione dello schema di convenzione, ai sensi dello stesso art.28 del D.P.R. 380 e relativa alla realizzazione di un altro <strong>fabbricato direzionale-residenziale<\/strong> in un&#8217;area ricadente in Zona territoriale omogenea F3, <strong>lungo via Giovanni e Francesca Falcone<\/strong>, angolo via Alessandro Lupinacci, \u00e8 stato illustrato sempre dal dirigente del settore Urbanistica, Francesco Azzato.<\/p>\n<p>&#8220;Anche in questo caso \u00e8 emersa la necessit\u00e0 \u2013 ha spiegato Azzato \u2013 di <strong>riapprovare lo schema di convenzione.<\/strong> La propriet\u00e0 del terreno proviene da una alienazione da parte del Comune. La destinazione urbanistica del terreno \u00e8 in zona territoriale F3 per cui l&#8217;edilizia che verr\u00e0 realizzata \u00e8 per il 70% residenziale e per il 30% direzionale. Il proponente si \u00e8 impegnato a realizzare a proprie spese interventi che riguardano sia la villetta comunale &#8220;Grazia Deledda&#8221; situata di fronte all&#8217;area di intervento, sia il riordino della segnaletica. Gli interventi consistono nella realizzazione di uno spazio giochi e di uno sgambatoio per animali&#8221;.<\/p>\n<h3>I dubbi del consigliere d&#8217;Ippolito<\/h3>\n<p>All&#8217;illustrazione del dirigente Azzato ha fatto seguito l&#8217;intervento del consigliere comunale Giuseppe d&#8217;Ippolito che ha mosso dei rilievi sul metodo adottato, sottolineando che la delibera di giunta risaliva ad appena venerd\u00ec scorso. &#8220;Noi \u2013 ha detto &#8211; l&#8217;abbiamo intravista solo ieri in una commissione svoltasi alla presenza del dirigente. Ci sono <strong>molte perplessit\u00e0.<\/strong> Verranno comunque pagati gli oneri di urbanizzazione&#8221;.<\/p>\n<p><strong>D&#8217;Ippolito ha sollevato dubbi sia sullo sgambatoio per cani<\/strong> che &#8220;sul non meglio precisato progetto per i <strong>giochi pubblici,<\/strong> evidenziando anche che con gli interventi sarebbe trasformata un&#8217;area parcheggio oggi al servizio della cittadinanza. Senza voler dubitare della correttezza della pratica \u2013 ha precisato d&#8217;Ippolito &#8211; si chiede di rinviarne la trattazione di una settimana, quindici giorni&#8221;.<\/p>\n<h3>L&#8217;appello di Bresciani: &#8220;Attenzione al verde&#8221;<\/h3>\n<p>A seguire, l&#8217;intervento della consigliera <strong>Alessandra Bresciani<\/strong> che ha ribadito, nel caso della realizzazione degli interventi, di tenere in <strong>debita considerazione il verde<\/strong>, con la previsione della messa a dimora di nuovi alberi. &#8220;Chiedo solo questa accortezza e di non trascurare questo aspetto in modo prioritario. Attenzione al verde!&#8221;.<\/p>\n<p>Ulteriori lumi sulla legittimit\u00e0 e correttezza dell&#8217;opera sono stati chiesti direttamente al dirigente Azzato dal consigliere Frammartino che, dichiaratosi sodddisfatto della risposta, ha preannunciato voto favorevole. La pratica \u00e8 poi passata con 17 voti a favore, mentre la minoranza, al momento del voto, ha abbandonato l&#8217;aula.<\/p>\n<p>Rinviati tuti gli altri punti all&#8217;ordine del giorno, tra cui la gestione da dare <a href=\"https:\/\/quicosenza.it\/news\/cosenza-parcheggi-coperti-e-strisce-blu-conscom\/\" target=\"_blank\" rel=\"noopener\">ai privati di parcheggio coperti e strisce blu.\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caldiero si aggiunge agli altri due componenti dell&#8217;organo di revisione risultati dal sorteggio effettuato: sono Antonio Pilello e Marcello Scarpelli <\/p>\n","protected":false},"author":90,"featured_media":297984,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-297983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/297983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/90"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=297983"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/297983\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/297984"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=297983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=297983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=297983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}