{"id":30021,"date":"2014-02-04T13:46:11","date_gmt":"2014-02-04T12:46:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-sud-sara-scosso-da-un-sisma-la-calabria-trema-impaurita\/"},"modified":"2023-01-17T12:46:30","modified_gmt":"2023-01-17T11:46:30","slug":"12621-il-sud-sara-scosso-da-un-sisma-la-calabria-trema-impaurita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12621-il-sud-sara-scosso-da-un-sisma-la-calabria-trema-impaurita\/","title":{"rendered":"ESCLUSIVA: Ipotizzato sisma di magnitudo 7.5 al Sud, il parere dell&#8217;esperto"},"content":{"rendered":"<p>COSENZA &#8211; La pericolosit\u00e0 sismica, secondo la definizione dettata dall\u2019Istituto Nazionale di Geofisica e Vulcanologia, \u00e8 \u201cla probabilit\u00e0 che un certo valore di scuotimento del suolo si verifichi in un dato intervallo di tempo\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Uno studio condotto, rispettivamente, dall\u2019Universit\u00e0 di Trieste e dall\u2019Accademia Russa delle Scienze, ha i<strong>potizzato un possibile terremoto, di notevole intensit\u00e0, al Sud Italia.<\/strong> Consapevoli dell\u2019impossibilit\u00e0 attuale di prevedere con sicurezza gli eventi tellurici Francesco Sposato, in un servizio condotto per la Redazione di RLB e andato in onda Mercoled\u00ec 5 Febbraio, ha chiesto delucidazioni all\u2019Ing. Alessandro Martelli, Presidente dell\u2019associazione GLIS e gi\u00e0 direttore del Centro Ricerche dell\u2019ENEA di Bologna.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00c8 da un po\u2019 di tempo, Ing. Martelli, che in rete leggiamo di forti preoccupazioni espresse di un possibile evento tellurico di forte intensit\u00e0 che potrebbe colpire il Sud Italia nel medio termine. Ci spiega su che basi si poggiano queste preoccupazioni e cosa si intende per medio termine?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Anzitutto premetto che io sono un ingegnere sismico, non un sismologo. I sismologi sono coloro che definiscono il movimento del terreno atteso durante un terremoto. A noi ingegneri spetta il compito finale: quello di fare in modo che le costruzioni, quando le realizziamo, siano in grado di resistere al terremoto, senza vittime e senza danni rilevanti, e quando analizziamo quelle gi\u00e0 esistenti, di verificare se tali requisiti sono raggiunti. Le preoccupazioni da lei citate sono state espresse dai sismologi triestini e russi; io, quale \u201cparte interessata\u201d, in considerazione della competenza di tali sismologi, mi sono limitato a trasmetterle all\u2019opinione pubblica, perch\u00e9 ritengo essa debba essere informata. <strong>Se fossimo in Giappone, dove le strutture sono ben costruite, non mi preoccuperei pi\u00f9 di tanto.<\/strong> Invece siamo in Italia, dove, purtroppo, come si \u00e8 accertato anche in sede istituzionale (nel 2012, nell\u2019ambito dell\u2019Indagine conoscitiva sullo stato della sicurezza sismica in Italia), oltre il 70% dell\u2019edificato esistente (inclusi molti edifici strategici e pubblici, come scuole, ospedali ed anche impianti chimici) non \u00e8 in grado di resistere ai terremoti ai quali potrebbe risultare soggetto.<\/p>\n<p>&nbsp;<\/p>\n<p>Noto che <strong>parliamo di terremoti gi\u00e0 avvenuti in passato, nelle diverse zone considerate, e che, pertanto, prima o poi ivi, con tutta probabilit\u00e0, si ripeteranno<\/strong>. Talvolta si tratta di eventi \u201crari\u201d, come quello che colp\u00ec l\u2019Emilia nel 2012 (l\u2019ultimo evento simile in Emilia Romagna risale al 1570). \u201cRaro\u201d non significa, per\u00f2, impossibile. In base ai loro studi, i sismologi che ho citato, grazie ai risultati dei loro cosiddetti \u201cesperimenti di previsione a medio termine\u201d, ci avvertono che il <strong>\u201cprima o poi\u201d potrebbe non essere troppo lontano nel tempo.<\/strong> Circa la validit\u00e0 di questi studi, ricordo che, per il Nord Italia, l\u2019allerta era stata comunicata alla Commissione Grandi Rischi il 1\u00b0 marzo 2012 ed ivi confermata, in mia presenza, in una riunione tenutasi il 4 maggio, cio\u00e8 prima del terremoto in Emilia Romagna. Ricordo anche che, fino ad ora, \u201cfalsi allarmi\u201d si sono verificati solo nel 30% dei casi. Mentre i russi si preoccupano dei megaterremoti a livello planetario (a loro si devono i timori per un terremoto di magnitudo superiore a 7 in un\u2019area che include Calabria Meridionale e Sicilia Orientale), i triestini limitano i loro studi alla sola Italia e, in accordo con dati a loro disposizione, si allertano se tali studi indicano il possibile superamento di valori di magnitudo assai inferiore a quella presa a riferimento dai russi (5,6 per il sud).<\/p>\n<p>&nbsp;<\/p>\n<p>Questi studi sono effettuati analizzando periodicamente, in ciascuna delle aree geografiche italiane considerate, gli eventi sismici di entit\u00e0 significativa (4,3 gradi Richter per il sud), quindi non troppo inferiore a quella dell\u2019evento ivi temibile (altrimenti sarebbe di poca validit\u00e0 qualsiasi estrapolazione). Per disporre di un numero sufficiente di eventi per le loro valutazioni, cos\u00ec come richiede qualsiasi analisi statistica, devono poi far riferimento a zone alquanto ampie: l\u2019Italia \u00e8, pertanto, suddivisa, dai triestini, in tre sole parti: nord, centro e sud, anche se non esattamente coincidenti con le omonime aree della cartina geografica. Semplificando, i sismologi, nel monitorare questi eventi, procedono come chi si misura costantemente la febbre: quando notano uno strano picco, verificano, in base ad opportune modellazioni, se si tratta di un \u201craffreddore\u201d ovvero possa temersi un inizio di \u201cpolmonite\u201d. Se, esaminando i dati, presumono che possa trattarsi di un inzio di polmonite, scatta la loro \u201callerta\u201d. Ovviamente, non possono azzardare ipotesi sul giorno esatto, e neppure su un ristretto periodo di tempo, in cui tale \u201cpolmonite\u201d potrebbe verificarsi. <strong>Possono solo stimare che essa possa colpire in un periodo che va da qualche mese ad uno o due anni.<\/strong> Avendo analizzato zone molto ampie, non possono azzardare ipotesi circa il luogo esatto in cui un terremoto maggiore dell\u2019intensit\u00e0 temuta potr\u00e0 verificarsi. Ovviamente, \u00e8 poi possibile che si tratti di un falso allarme.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ma non \u00e8 meglio un falso allarme, se motivato, rispetto ad uno trascurato? Cosa pu\u00f2 fare la popolazione a riguardo e cosa, invece, dovrebbero fare le Istituzioni?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>In Italia c\u2019\u00e8 una scarsissima percezione del richio sismico, sia nell\u2019opinione pubblica che, conseguentemente, nelle Istituzioni. \u00c8 questo il motivo per il quale, non essendosi mai fatta una seria prevenzione sismica, si \u00e8 accumulato l\u2019enorme numero di costruzioni insicure che ho citato<strong>. Ormai le tecnologie per rendere le costruzioni sicure, come in Giappone, esistono anche in Italia. Applicarle ha ovviamente un costo<\/strong>, soprattutto per intervenire sull\u2019esistente. Ma anche la vita umana ha un valore, o no?. Per\u00f2 la popolazione, anche attraverso la paura suscitata dagli eventi di questi mesi, deve acquisire coscienza: molte cose le possono fare anche i singoli, verificando, ad esempio, la sicurezza delle loro case e quella delle scuole frequentate dai loro figli, sistemando le prime e pretendendo sicurezza per le seconde, nonch\u00e9, se necessario, spostando i loro figli in edifici sufficientemente sicuri (alcuni esistono). I singoli possono poi spronare le Istituzioni a fare il loro dovere (i politici ci tengono ai voti &#8230;). Le Istituzioni, come ho detto, dovrebbero fare il loro dovere, cio\u00e8 attivare finalmente adeguate politiche di prevenzione. Nessuno ha scuse, perch\u00e9, come ho sottolineato, le tecnologie atte a rendere sicura qualsiasi costruzione esistono. E non si accampi la scusa, per continuare a non far nulla, che la spesa da affrontare per sistemare l\u2019edificato esistente \u00e8 enorme.<\/p>\n<p>&nbsp;<\/p>\n<p>Ci\u00f2 \u00e8 vero e nessuno pretende che essa sia affrontata tutta subito, <strong>ci vorranno 50-60 anni per rendere resistente al terremoto l\u2019edificato esistente<\/strong>, ma, se non si comincia mai, il problema (morti e costi) sar\u00e0 da noi quantomeno \u201cregalato\u201d alle future generazioni . I costi della ricostruzione dopo un terremoto sono circa cinque volte maggiori della spesa che si sarebbe dovuta affrontare per rendere sicure le costruzioni prima del suo accadimento. Quindi la scusa dei costi non sta in piedi. Un paese civile dovrebbe mettere a bilancio, ogni anno, una spesa per la prevenzione. E per stabilire dove cominciare a spendere, anche gli \u201cesperimenti di previsione\u201d dei terremoti potranno essere molto utili. Cos\u00ec come questi \u201cesperimenti\u201d, contrariamente a ci\u00f2 che qualcuno va dicendo, sono utili anche nel medio termine: non certamente per evacuare per mesi ampie zone, bens\u00ec, ad esempio, per verificare l\u2019adeguatezza delle strutture pi\u00f9 importanti, per organizzare la protezione civile e per dare la necessaria informazione alla popolazione. Anche se il terremoto non dovesse avvenire nell\u2019area allertata nei tempi temuti, non sarebbero mai soldi buttati, perch\u00e9 si salver\u00e0 tale area (abitanti in primis) in futuro. Termino con l\u2019informazione alla popolazione: \u00e8 dovere delle Istituzioni attivare misure preventive a tappeto e da subito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La pericolosit\u00e0 sismica, secondo la definizione dettata dall\u2019Istituto Nazionale di Geofisica e Vulcanologia, \u00e8 \u201cla probabilit\u00e0 che un certo valore di scuotimento del suolo si verifichi in un dato intervallo di tempo\u201d.<\/p>\n","protected":false},"author":22,"featured_media":30022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-30021","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30021","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30021"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30021\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30022"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30021"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30021"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30021"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}