{"id":30099,"date":"2014-02-06T09:23:06","date_gmt":"2014-02-06T08:23:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/a-trebisacce-inaugurato-il-nuovo-polo-scolastico\/"},"modified":"2023-01-17T12:46:35","modified_gmt":"2023-01-17T11:46:35","slug":"12661-a-trebisacce-inaugurato-il-nuovo-polo-scolastico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12661-a-trebisacce-inaugurato-il-nuovo-polo-scolastico\/","title":{"rendered":"A Trebisacce inaugurato il nuovo polo scolastico"},"content":{"rendered":"<p>TREBISACCE (CS) &#8211; Taglio del nastro ieri, per il nuovo polo scolastico di Trebisacce.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il primo cittadino Francesco Mundo, insieme al presidente della provincia Mario Oliverio, hanno presenziato l&#8217;importante momento al quale sono intervenuti, tra gli altri, l&#8217;assessore provinciale alla Pubblica Istruzione Maria Francesca Corigliano, la Dirigente Scolastica Elisabetta Cataldi e numerosi sindaci tra i quali Roberto Rizzuto, sindaco di Villapiana, Gianni Papass sindaco di Cassano e Antonio Carlomagno, primo cittadino di Cerchiara. Al termine degli interventi ha chiuso la manifestazione il coro della &#8220;G. Mahler&#8221; che ha intonato due brani noti dell&#8217;importante e straordinario patrimonio musicale italiano. Circa 3 milioni di euro, \u00e8 la cifra dell\u2019investimento finanziato dalla Provincia di Cosenza per la realizzazione ex novo di questa nuova infrastruttura sportiva a disposizione del territorio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TREBISACCE (CS) &#8211; Taglio del nastro ieri, per il nuovo polo scolastico di Trebisacce.<\/p>\n","protected":false},"author":19,"featured_media":30100,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-30099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30099"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30099\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30100"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}