{"id":30169,"date":"2014-02-07T13:36:37","date_gmt":"2014-02-07T12:36:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/la-regione-vuole-piazzare-un-inceneritore-a-cosenza\/"},"modified":"2023-01-17T12:46:41","modified_gmt":"2023-01-17T11:46:41","slug":"12702-la-regione-vuole-piazzare-un-inceneritore-a-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12702-la-regione-vuole-piazzare-un-inceneritore-a-cosenza\/","title":{"rendered":"L&#8217;assessore accusato di disastro ambientale vuole un inceneritore a Cosenza"},"content":{"rendered":"<p>RENDE &#8211; &#8220;L\u2019emergenza rifiuti non \u00e8 causata dai rifiuti dei cosentini, ma dal malgoverno regionale.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Mentre a Bucita c\u2019\u00e8 chi resiste, l\u2019assessore Pugliano continua a fuggire&#8221;. Le accuse sono indirizzate all&#8217;assesore regionale all&#8217;ambiente autore di un piano per la gestione rifiuti che intende avviare la faraonica opera di installare un inceneritore in ogni provincia calabrese. Una vera e propria follia se si pensa alla vocazione turistica ed agricola del territorio calabrese. Una follia che il collettivo Laboratorio Politico P2 Occupata non intende assecondare. &#8220;La fuga dell\u2019assessore Pugliano, &#8211; si legge in una nota divulgata dagli attivisti del Laboratorio Politico &#8211; avvenuta l\u2019altro giorno dalla sala stampa dell\u2019Universit\u00e0 della Calabria, \u00e8 significativa della situazione in cui versa la nostra regione. Ha lasciato di corsa la presentazione della candidatura del Parco della Sila tra i patrimoni Unesco per recarsi in giunta. Questo perch\u00e9 la discarica su cui si regge l\u2019intero smaltimento dei rifiuti regionale \u00e8 chiusa ancora una volta a causa della pioggia. Andandosene dalla conferenza, ha avuto solo il tempo di annunciare una nuova emergenza e di dire quello che \u00e8 diventato il suo mantra: <strong>\u201cbisogna costruire nuovi impianti, l\u2019emergenza \u00e8 provocata dai rifiuti dei cosentini\u201d<\/strong>. Ma il problema rifiuti \u00e8 di fronte ad ogni calabrese e non pu\u00f2 essere nascosto sotto il tappeto. Una emergenza che dura paradossalmente da pi\u00f9 di quindici anni \u00e8 difficile da nascondere.<\/p>\n<p>Infatti, niente \u00e8 migliorato da quando, oramai due anni fa, contestammo Pugliano in quella stessa sala stampa. Come Rete in Difesa del Territorio \u201cF. Nistic\u00f2\u201d eravamo l\u00ec per chiedere le sue dimissioni e la fine del commissariamento. Ci trovavamo di fronte un assessore responsabile sul piano politico e sul piano giudiziario: veniva a parlare di educazione ambientale un indagato per la discarica di All\u00ec. La<strong> sua posizione si \u00e8 ora aggravata perch\u00e9 accusato di disastro ambientale: il percolato che inquina il fiume All\u00ec porta il nome anche di un assessore regionale all\u2019ambiente.<\/strong> <strong>Cosa aspetta a dimettersi?<\/strong><br \/>Il lato peggiore di Pugliano, per\u00f2, si vede sul territorio calabrese negli altri scempi di cui \u00e8 colpevole per il suo ruolo politico. Stando ai fatti, c\u2019\u00e8 stata una precisa scelta politica nell\u2019avallare la speculazione sull\u2019emergenza rifiuti ai danni della salute dei calabresi. La raccolta differenziata e la riduzione del rifiuto, infatti, sarebbero l\u2019unica soluzione virtuosa a questo scempio (come ampiamente dimostrato dalla strategia \u201crifiuti zero\u201d). Questo per\u00f2 intaccherebbe i profitti di chi oggi si arricchisce avvelenando i territori. Invece che i cittadini, l\u2019assessore regionale Pugliano sembra voler difendere proprio questi interessi, come confermato dai dati della raccolta differenziata. La raccolta differenziata in Calabria semplicemente non esiste e anche gli impianti di selezionamento cadono a pezzi e sono inservibili, come confermato dagli stessi dati della regione. Imporre nuovi impianti ai cittadini (senza nemmeno confontarsi con loro) avrebbe l\u2019unico scopo di continuare a speculare sugli appalti e sull\u2019economia da rifiuto. Questo vuol dire mettere la Calabria nelle mani di speculatori grandi e piccoli e della \u2018ndrangheta.<\/p>\n<p>&nbsp;<\/p>\n<p>Non si fa niente per arginare questo fenomeno che \u00e8 la vera causa dell\u2019emergenza e, anzi, d<strong>ai documenti e dalle dichiarazioni della regione si legge l\u2019intenzione di continuare a seguire la via pericolosa dell\u2019incenerimento e delle mega-discariche. Un finanziamento legalizzato all\u2019avvelenamento dei territori.<\/strong> Non vogliono trovare i fondi necessari per costruire un sistema di gestione virtuoso, altro che colpa dei rifiuti cosentini. Vogliamo dire chiaro che nell\u2019area urbana i problemi dell\u2019inquinamento sono anche troppi ed \u00e8 inaccettabile che a questi si aggiunga l\u2019apertura di un impianto di incenerimento o trattamento. Questi impianti potrebbero solo inserirsi nel quadro di pura speculazione sopra descritta e nell\u2019ottica di soluzioni tampone che, come si \u00e8 visto, non fanno che allungare la decennale emergenza. <strong>Le popolazioni stanno dicendo chiaro il loro no a soluzioni tampone come quella di Albicello a Donnici,<\/strong> contro cui coraggiosamente si batte il Comitato Difesa Territorio &#8211; Donnici.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A proposito di emergenze ambientali, sappiamo bene qual\u2019\u00e8 la priorit\u00e0 dell\u2019area urbana cosentina: l\u2019inquinamento della ex \u2013 Legnochimica, che da decenni semina morti tra i residenti e inquina gli studenti che vengono all\u2019UniCal<\/strong>. La difesa dei nostri territori viene dai calabresi che lottano e si impegnano in prima persona per fermare questo sistema. Un sistema che si regge grazie ai disegni che portano anche la firma di Pugliano. Non da ultimo il bando regionale di smaltimento dei rifiuti, contro cui stanno lottando i cittadini del Comitato in difesa di Bucita riuniti nel blocco dell\u2019impianto. Basta decidere sulle spalle delle comunit\u00e0. Questo bando non deve passare. Ci sentiamo vicini a loro come a chiunque si impegni in difesa del proprio territorio in prima persona contro quell\u2019inquinamento che colpisce anche la classe dirigente. E\u2019 dalla Calabria che resiste che viene l\u2019energia per invertire la rotta e rimettere al centro il diritto alla salute, la partecipazione e il controllo diretto da parte dei cittadini&#8221;.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; &#8220;L\u2019emergenza rifiuti non \u00e8 causata dai rifiuti dei cosentini, ma dal malgoverno regionale.<\/p>\n","protected":false},"author":22,"featured_media":30170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-30169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30169"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30170"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}