{"id":30199,"date":"2014-02-08T13:20:49","date_gmt":"2014-02-08T12:20:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/cappellacci-chiede-al-cosenza-la-massima-attenzione\/"},"modified":"2023-01-17T12:46:45","modified_gmt":"2023-01-17T11:46:45","slug":"12730-cappellacci-chiede-al-cosenza-la-massima-attenzione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12730-cappellacci-chiede-al-cosenza-la-massima-attenzione\/","title":{"rendered":"Cappellacci chiede al Cosenza la massima attenzione"},"content":{"rendered":"<p><span style=\"background-color: rgba(255, 255, 255, 0);\">COSENZA &#8211; Il Cosenza \u00e8 pronto per affrontare il Castel Rigone, questa la rassicurazione di Cappellacci.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"background-color: rgba(255, 255, 255, 0);\">&#8220;Premettiamo che si pu\u00f2 perdere&#8221; queste le prime parole del tecnico&nbsp;<strong>rosso<\/strong>&nbsp;<strong>blu<\/strong>, che giustifica la non brillante prestazione contro&nbsp;<strong>l&#8217;Arzanese<\/strong>. &#8220;\u00c8 un campionato complicato per tutti, dove ogni squadra pu\u00f2 trovare difficolt\u00e0 e trovarsi a fare i conti con chiunque. Quello che pretendo dai miei ragazzi \u00e8 avere la giusta attenzione, affrontando gli avversari con la giusta determinazione, anche perch\u00e9 le insidie sono sempre in agguato, a prescindere dall&#8217;aver ottenuto tanti punti, la mia squadra deve sempre avere ben presente che deve dare sempre il meglio ed impegnarsi costantemente.&#8221; Il tecnico&nbsp;<strong>rosso<\/strong>&nbsp;<strong>blu<\/strong>&nbsp;ha speso parole di elogio per il&nbsp;<strong>Castel<\/strong>&nbsp;<strong>Rigone<\/strong>&nbsp;affermando che gli&nbsp;<strong>umbri<\/strong>&nbsp;&#8220;sono una squadra da affrontare con la massima concentrazione essendo compagine di valore e di indubbie qualit\u00e0 tecniche, ed aggiungo che i&nbsp;<strong>perugini<\/strong>&nbsp;possono essere paragonati benissimo al&nbsp;<strong>Cosenza<\/strong>.&#8221; Per quanto riguarda la squadra che scender\u00e0 in campo contro il&nbsp;<strong>Castel<\/strong>&nbsp;<strong>Rigone<\/strong>, il tecnico&nbsp;<strong>rosso<\/strong>&nbsp;<strong>blu<\/strong>&nbsp;ha confermato che &#8220;ci saranno sicuramente delle variazioni nella formazione, visto i rientri di&nbsp;<strong>Mosciaro<\/strong>&nbsp;e&nbsp;<strong>De<\/strong>&nbsp;<strong>Angelis<\/strong>&nbsp;in attacco e di&nbsp;<strong>Asante<\/strong>&nbsp;a centrocampo, per quanto riguarda il settore arretrato sto valutando qualche variazione, ma sia ben chiaro che se anche dovesse esserci qualche avvicendamento, non sar\u00e0 una bocciatura per nessuno.&#8221; Un &nbsp;pensiero finale \u00e8 rivolto un po&#8217; a tutti i suoi giocatori, &#8220;che dovranno essere pi\u00f9 attenti e non ripetere gli errori di domenica scorsa.&#8221;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Cosenza \u00e8 pronto per affrontare il Castel Rigone, questa la rassicurazione di Cappellacci.<\/p>\n","protected":false},"author":22,"featured_media":30200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-30199","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30199","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30199"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30199\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30200"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30199"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30199"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30199"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}