{"id":302315,"date":"2026-09-02T20:56:59","date_gmt":"2026-09-02T18:56:59","guid":{"rendered":"https:\/\/quicosenza.it\/news\/?p=302315"},"modified":"2026-09-02T20:56:59","modified_gmt":"2026-09-02T18:56:59","slug":"movimento-rinasci-cosenza-2027-primarie","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/movimento-rinasci-cosenza-2027-primarie\/","title":{"rendered":"Movimento Rinasci Cosenza: \u00abBasta candidati calati dall&#8217;alto. Per il 2027 Cosenza merita il coraggio delle primarie\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Il<strong> rincorrersi quotidiano di indiscrezioni, pour-parler e toto-nomi in vista delle elezioni comunali di Cosenza del 2027 restituisce l&#8217;immagine di una politica vecchia, autoreferenziale e distante dai reali bisogni della citt\u00e0. D<\/strong>iscussioni da bar e caminetti chiusi non sono e non saranno mai il metodo adeguato per costruire una proposta di governo solida e innovativa per una comunit\u00e0 che ha disperatamente bisogno di un rilancio strutturale e di una vera rinascita&#8221;.<\/p>\n<p>Il <a href=\"https:\/\/smartcosenza.org\/\" target=\"_blank\" rel=\"noopener\"><strong>Movimento Rinasci Cosenza<\/strong><\/a> prende le distanze da questa logica opaca e lancia una sfida netta e aperta a tutte le forze politiche e alle coalizioni che scenderanno in campo per la competizione elettorale.<\/p>\n<p>Basta scegliere i candidati a sindaco nelle segrete stanze dei partiti. Basta subire diktat e decisioni calate dall&#8217;alto, decise nei palazzi romani da chi ignora le emergenze, le potenzialit\u00e0 e le ferite quotidiane del nostro territorio.<br \/>\nCosenza non \u00e8 una casella da occupare o una merce di scambio nei tavoli provinciali o nazionali, ma una comunit\u00e0 viva che deve tornare a essere protagonista del proprio destino.<\/p>\n<p>Esiste uno strumento principe, democratico e trasparente per restituire la voce e il potere di scelta ai cittadini: le primarie aperte e partecipate.<\/p>\n<p><strong>Rinasci Cosenza invita dunque tutte le coalizioni e i movimenti civici a sottoscrivere un patto di coerenza democratica<\/strong>. Chi ha a cuore le sorti di <a href=\"https:\/\/quicosenza.it\/news\/primarie-pd-buona-laffluenza-al-seggio-di-cosenza-centro\/\" target=\"_blank\" rel=\"noopener\">Cosenza<\/a> rifiuti i nomi preconfezionati. Si scelga il candidato a sindaco attraverso il confronto pubblico, nei quartieri, tra la gente, affidando alla cittadinanza il compito di selezionare la guida per la Cosenza del 2027. La rinascita della citt\u00e0 comincia dal metodo: se si vuole cambiare, bisogna avere il coraggio di affidarsi ai cittadini&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il movimento Rinasci Cosenza attacca i retroscena sulle Comunali 2027 e lancia un ultimatum ai partiti: \u00abNo ai candidati decisi a Roma, si usino le primarie aperte\u00bb<\/p>\n","protected":false},"author":58,"featured_media":294578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[],"class_list":["post-302315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/302315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=302315"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/302315\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/294578"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=302315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=302315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=302315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}