{"id":30474,"date":"2014-02-18T08:04:05","date_gmt":"2014-02-18T07:04:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-punto-sul-ventiquattresimo-turno-di-lega-pro-2-gir-b\/"},"modified":"2023-01-17T12:47:49","modified_gmt":"2023-01-17T11:47:49","slug":"12872-il-punto-sul-ventiquattresimo-turno-di-lega-pro-2-gir-b","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12872-il-punto-sul-ventiquattresimo-turno-di-lega-pro-2-gir-b\/","title":{"rendered":"Il punto sul ventiquattresimo turno di Lega pro 2 gir. B"},"content":{"rendered":"<p>COSENZA &#8211; Ventiquattresimo turno di campionato caratterizzato da ben cinque vittorie esterne, due pareggi e due sole vittorie delle squadre di casa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nell&#8217;anticipo del venerd\u00ec sera, il <strong>Messina<\/strong> riesce nell&#8217;impresa di violare lo <strong>Zaccheria<\/strong> di <strong>Foggia<\/strong> imponendosi sui padroni di casa, i <strong>peloritani<\/strong> &nbsp;hanno dimostrato di possedere qualit\u00e0 tecniche e soluzioni tattiche che permetteranno alla squadra di <strong>Grassadonia<\/strong> di approdare con tranquillit\u00e0 alla <strong>Lega<\/strong> pro unica. Da parte sua, il <strong>Foggia<\/strong> \u00e9 sembrato meno brillante del solito, evidenziando un calo fisico, che a questo punto della stagione ci pu\u00f2 stare. Continua la marcia inarrestabile della <strong>Casertana<\/strong>, che con il minimo sforzo ottiene il massimo del profitto, battendo a domicilio il <strong>Castel<\/strong> <strong>Rigone<\/strong>, che pur rimasto in dieci uomini ha saputo mettere in difficolt\u00e0 la capolista, sbagliando anche un calcio di rigore. Continua il calvario del <strong>Sorrento<\/strong> sul campo amico, questa volta \u00e8 il turno <strong>dell&#8217;Ischia<\/strong> a prendersi i tre punti in palio e lasciando ai padroni di casa l&#8217;ennesima amarezza della stagione, <strong>sorrentini<\/strong> ormai ad un passo dalla retrocessione. Ennesima vittoria esterna esterna del <strong>Chieti<\/strong> in trasferta, vittima di turno \u00e9 <strong>l&#8217;Aversa<\/strong>, che nelle ultime giornate sembra avere qualche problema di tenuta fisica, pagando probabilmente il gran girone d&#8217;andata disputato. Vince soffrendo il <strong>Teramo<\/strong>, che con il minimo scarto batte un <strong>Martina<\/strong> mai domo, che non avrebbe meritato la sconfitta per la grande mole di gioco messa in atto nell&#8217;arco della gara. Pari fra <strong>Arzanese<\/strong>&#8211; <strong>Tuttocuio<\/strong>, risultato che serve molto di pi\u00f9 ai <strong>toscani<\/strong>, i quali con una reazione veemente hanno rimontato i due goal di svantaggio. <strong>Campani<\/strong> invece che potrebbero pagare a caro prezzo il fatto di aver mancato i tre punti in palio. Pareggia in casa la <strong>Vigor<\/strong> <strong>Lamezia<\/strong> contro il fanalino di coda <strong>Gavorrano<\/strong>, risultato questo, che costa l&#8217;esonero al tecnico dei bianco verdi <strong>Novelli<\/strong>. Torna a vincere in trasferta il <strong>Cosenza<\/strong>, che con una gara attenta ed essenziale batte un ostico <strong>Melfi<\/strong>. I ragazzi di <strong>Cappellacci<\/strong> hanno interpretato la partita nel migliore dei modi, tornando ad essere quella squadra ammirata fino a qualche partita addietro, che concedeva poco agli avversari e capitalizzava al massimo le occasioni che capitavano. Del <strong>Cosenza<\/strong> \u00e8 piaciuto sopratutto il carattere e la voglia di vincere, qualit\u00e0 queste che potranno essere determinanti per la vittoria finale del campionato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Ventiquattresimo turno di campionato caratterizzato da ben cinque vittorie esterne, due pareggi e due sole vittorie delle squadre di casa.<\/p>\n","protected":false},"author":22,"featured_media":30475,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-30474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30474"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30475"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}