{"id":30604,"date":"2014-02-21T09:38:47","date_gmt":"2014-02-21T08:38:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/agroalimentare\/"},"modified":"2023-01-17T12:47:57","modified_gmt":"2023-01-17T11:47:57","slug":"12939-agroalimentare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12939-agroalimentare\/","title":{"rendered":"Caciocavallo Dop senza tracciabilit\u00e0, 8mila euro di multe"},"content":{"rendered":"<p>LAMEZIA TERME &#8211; Prodotti tipici confezionati con marchio Dop ed Igp, ma senza provenienza.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Stamane il Corpo forestale dello Stato di Lamezia Terme ha scoperto l&#8217;utilizzo irregolare delle denominazioni protette su alcuni cibi in vendita sugli scaffali di alimentari e supermercati. Le etichette pare siano state usate in modo tale da non consentire la tracciabilit\u00e0 dei prodotti in questione. Prodottti di qualit\u00e0, eccellenze della tradizione agroalimentare destinati al largo consumo come caciocavallo, prosciutto crudo, spek e mortadella. Ai responsabili degli esercizi commerciali in cui sono stati ritrovati i cibi senza tracciabilit\u00e0 sono state contestate violazioni amministrative per un ammontare totale di ottomila euro. L&#8217;operazione si inserisce in una serie di controlli avviati dai forestali e finalizzati alla tutela dei prodotti agroalimentari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME &#8211; Prodotti tipici confezionati con marchio Dop ed Igp, ma senza provenienza.<\/p>\n","protected":false},"author":22,"featured_media":30605,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-30604","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30604"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30604\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30605"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}