{"id":30670,"date":"2014-02-24T10:12:27","date_gmt":"2014-02-24T09:12:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/appalti-sequestrati-documenti-al-comune-di-reggio-calabria\/"},"modified":"2023-01-17T12:48:02","modified_gmt":"2023-01-17T11:48:02","slug":"12975-appalti-sequestrati-documenti-al-comune-di-reggio-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12975-appalti-sequestrati-documenti-al-comune-di-reggio-calabria\/","title":{"rendered":"Appalti: sequestrati documenti al Comune di Reggio Calabria"},"content":{"rendered":"<p>REGGIO CALABRIA (RC) &#8211; Gestione anomale nelle societ\u00e0 partecipate del settore dei rifiuti e manutenzione.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Appalti pubblici non troppo chiari affidati a due aziende miste, Leonia e Multiservizi sciolte per interdittiva antimafia. Il socio privato che divideva la propriet\u00e0 con il Comune di Reggio Calabria colpito dall&#8217;antimafia ha fatto forse scattare i campanelli dall&#8217;allarme dei commissari. Sono cos\u00ec stati acquisiti dall&#8217;autorit\u00e0 giudiziaria nel Comune di Reggio Calabria gli atti relativi alle relazioni tra l&#8217;ente e le societ\u00e0 esternalizzate e partecipate dell&#8217;ente. L&#8217;acquisizione \u00e8 stata effettuata da un gruppo interforze composto da polizia, carabinieri e guardia di finanza in esecuzione di un provvedimento emesso dal Procuratore della Repubblica, Federico Cafiero de Raho. La richiesta \u00e8 stata notificata alla terna commissariale, presieduta dal prefetto Gaetano Chiusolo, che gestisce il Comune dopo lo scioglimento deciso nel 2012 dal Consiglio dei ministri per contiguit\u00e0 con la &#8216;ndrangheta. Il commissariamento del Comune, nei giorni scorsi, \u00e8 stato prorogato per altri sei mesi. &#8220;Si tratta di una indagine in corso &#8211; affermano fonti della Procura &#8211; per verificare elementi utili ai fini della corretta gestione delle societ\u00e0 partecipate&#8221;. Un pool interforze composto da uomini di Polizia, Carabinieri e Guardia di Finanza, ha quindi sequestrato a Palazzo San Giorgio, sede del Comune di Reggio Calabria, documenti riguardanti appalti e affidamenti nei settori dei rifiuti e della manutenzione nel periodo ricompreso dalla nascita delle societa&#8217; miste Leonia e Multiservizi fino ad oggi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA (RC) &#8211; Gestione anomale nelle societ\u00e0 partecipate del settore dei rifiuti e manutenzione.<\/p>\n","protected":false},"author":22,"featured_media":30671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-30670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30670"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30671"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}