{"id":30686,"date":"2014-02-24T14:11:05","date_gmt":"2014-02-24T13:11:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/centenario-cosenza-calcio-lo-spettacolo-del-s-vito\/"},"modified":"2023-01-17T12:48:02","modified_gmt":"2023-01-17T11:48:02","slug":"12983-centenario-cosenza-calcio-lo-spettacolo-del-s-vito","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/12983-centenario-cosenza-calcio-lo-spettacolo-del-s-vito\/","title":{"rendered":"Centenario Cosenza Calcio lo spettacolo del San Vito (FOTOGALLERY)"},"content":{"rendered":"<p>COSENZA &#8211; Una giornata indimenticabile per chi era al S. Vito ieri a festeggiare il Cosenza Calcio.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Riviviamo le emozioni attraverso alcuni scatti di Ernesto Pescatore e Riccardo Tucci. (1 &#8211; continua) {imageshow sl=82 sc=3 \/}<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Una giornata indimenticabile per chi era al S. Vito ieri a festeggiare il Cosenza Calcio.<\/p>\n","protected":false},"author":22,"featured_media":30687,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-30686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30686"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30686\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30687"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}