{"id":30799,"date":"2014-02-28T07:59:58","date_gmt":"2014-02-28T06:59:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/anatomy-awards-statuette-senza-veli-per-gli-oscar-del-nudo-2014\/"},"modified":"2023-01-17T12:48:10","modified_gmt":"2023-01-17T11:48:10","slug":"13044-anatomy-awards-statuette-senza-veli-per-gli-oscar-del-nudo-2014","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13044-anatomy-awards-statuette-senza-veli-per-gli-oscar-del-nudo-2014\/","title":{"rendered":"Anatomy Awards, statuette senza veli per gli Oscar del nudo 2014"},"content":{"rendered":"<p>Mancano pochi giorni alla consegna degli Oscar e, come ogni anno, il sito Mr Skin anticipa l&#8217;Academy assegnando gli &#8220;Anatomy Awards&#8221;, ovvero i premi ai protagonisti delle migliori scene senza veli dell&#8217;anno passato. Tra i &#8220;premiati&#8221; di quest&#8217;anno Emily Ratajkowski, l&#8217;immancabile Miley Cyrus, il film di Martin Scorsese &#8220;The Wolf Of Wall Street&#8221; e, tra le serie tv, &#8220;Masters Of Sex&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mancano pochi giorni alla consegna degli Oscar e, come ogni anno, il sito Mr Skin anticipa l&#8217;Academy assegnando gli &#8220;Anatomy Awards&#8221;, ovvero i premi ai protagonisti delle migliori scene senza veli dell&#8217;anno passato. Tra i &#8220;premiati&#8221; di quest&#8217;anno Emily Ratajkowski, l&#8217;immancabile Miley Cyrus, il film di Martin Scorsese &#8220;The Wolf Of Wall Street&#8221; e, tra [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":30800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,40,34],"tags":[],"class_list":["post-30799","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30799"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30799\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30800"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}