{"id":30867,"date":"2014-03-03T05:51:18","date_gmt":"2014-03-03T04:51:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/erano-andati-sul-pollino-a-vedere-la-neve-ma-finiscono-in-un-burrone-morto-giovane-veterinario\/"},"modified":"2023-01-17T12:48:38","modified_gmt":"2023-01-17T11:48:38","slug":"13078-erano-andati-sul-pollino-a-vedere-la-neve-ma-finiscono-in-un-burrone-morto-giovane-veterinario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13078-erano-andati-sul-pollino-a-vedere-la-neve-ma-finiscono-in-un-burrone-morto-giovane-veterinario\/","title":{"rendered":"Erano andati sul Pollino per la neve, finiscono in un burrone. Morto veterinario"},"content":{"rendered":"<p>ALESSANDRIA DEL CARRETTO (CS) &#8211; Un giovane veterinario Marco Arvia, di 27 anni, e\u2019 morto in un incidente stradale avvenuto nella zona del Parco del Pollino.<\/p>\n<p>  <!--more-->  <\/p>\n<p>L\u2019auto, una Fiat Panda 4X4 condotta dalla vittima, per cause in corso di accertamento, e\u2019 precipitata da un burrone profondo circa cento metri. Due persone di 24 e 14 anni che erano con lui, sono rimaste ferite dopo essere state sbalzate fuori dall\u2019abitacolo e trasferite in ambulanza nell&#8217;ospedale di Rossano. I tre avevano deciso di recarsi sul monte Sparviero per un\u2019escursione sulla neve. E proprio a causa della fitta nevicata e del luogo impervio, sono stati particolarmente difficoltosi i soccorsi operati dai Vigili del Fuoco che hanno recuperato il due feriti G.B., 23 anni ed il minore G.A. di 14, e il corpo senza vita del giovane veterinario. L\u2019incidente \u00e8 avvenuto nella notte tra sabato e domenica, intorno alle 2. Il corpo di Arvia su disposizione dell\u2019autorit\u00e0 giudiziaria, \u00e8 stato trasportato nell\u2019obitorio dell\u2019ex ospedale di Trebisacce in attesa dell\u2019esame autoptico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ALESSANDRIA DEL CARRETTO (CS) &#8211; Un giovane veterinario Marco Arvia, di 27 anni, e\u2019 morto in un incidente stradale avvenuto nella zona del Parco del Pollino.<\/p>\n","protected":false},"author":19,"featured_media":30868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-30867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30867"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30868"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}