{"id":30875,"date":"2014-03-03T08:18:39","date_gmt":"2014-03-03T07:18:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/lattarico-ubriaco-picchia-la-convivente-incinta-arrestato-25enne\/"},"modified":"2023-01-17T12:48:38","modified_gmt":"2023-01-17T11:48:38","slug":"13082-lattarico-ubriaco-picchia-la-convivente-incinta-arrestato-25enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13082-lattarico-ubriaco-picchia-la-convivente-incinta-arrestato-25enne\/","title":{"rendered":"Lattarico, ubriaco picchia la convivente incinta. Arrestato 25enne"},"content":{"rendered":"<p>LATTARICO (CS) &#8211; Ha picchiato la compagna, incinta, davanti al figlio in preda ai fumi dell&#8217;alcol.<\/p>\n<p>  <!--more-->  <\/p>\n<p>I carabinieri di Lattarico, nel Cosentino, hanno arrestato, in flagranza di reato, un giovane di 25 anni, Albino Lupo, artigiano, gi\u00e0 noto alle forze dell&#8217;ordine. Il giovane, durante i festeggiamenti di Carnevale a Regina, frazione di Lattarico, si e&#8217; ubriacato e poi ha picchiato la propria convivente, incinta, davanti al figlio di tre anni. Il fatto e&#8217; avvenuto in auto, ma poi e&#8217; continuato per strada, in presenza di altri familiari che hanno tentato di bloccarlo. La donna si trova adesso ricoverata nell&#8217;ospedale di Cosenza con una minaccia d&#8217;aborto e prognosi di 14 giorni. L&#8217;uomo e&#8217; stato portato nel carcere di Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LATTARICO (CS) &#8211; Ha picchiato la compagna, incinta, davanti al figlio in preda ai fumi dell&#8217;alcol.<\/p>\n","protected":false},"author":19,"featured_media":30876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-30875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30875"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30876"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}