{"id":30893,"date":"2014-03-03T14:21:30","date_gmt":"2014-03-03T13:21:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/le-pagelle-di-foggia-cosenza\/"},"modified":"2023-01-17T12:48:39","modified_gmt":"2023-01-17T11:48:39","slug":"13091-le-pagelle-di-foggia-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13091-le-pagelle-di-foggia-cosenza\/","title":{"rendered":"Le pagelle di Foggia-Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; Il Cosenza torna da Foggia con una sconfitta che, con una partita pi\u00f9 convinta poteva essere evitata.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>Frattali<\/strong>: una partita in cui non sporca nemmeno i guanti <strong>S<\/strong>.<strong>V.<\/strong><br \/><strong>Bigoni<\/strong>: solita prestazione di carattere, annulla Cavallaro e non disdegna di aiutare la squadra nel gioco d&#8217;attacco <strong>6<\/strong>.<strong>5<\/strong><br \/><strong>Mannini<\/strong>: non attraversa un buon momento di forma,soffre quando viene attaccato <strong>5<\/strong><br \/><strong>Giordano<\/strong>: torna titolare, fornendo una prestazione di tutto rispetto <strong>6<\/strong><br \/><strong>Blondett<\/strong>: lotta su ogni pallone, garantendo alla retroguardia sicurezza <strong>6<\/strong>.<strong>5<\/strong><br \/><strong>Guidi<\/strong>: come al solito si mette in risalto per la grande esperienza <strong>6<\/strong><br \/><strong>Asante<\/strong>: parte bene, garantendo il giusto equilibrio al centrocampo, cala alla distanza <strong>6<\/strong><br \/><strong>Corsi<\/strong>: buono in fase di interdizione, non ripete per\u00f2 la buona prova di domenica scorsa in fase di costruzione <strong>6<\/strong><br \/><strong>De<\/strong> <strong>Angelis<\/strong>: lasciato troppo solo, sbatte contro il muro dei difensori foggiani, il suo impegno \u00e9 massimo <strong>6<\/strong><br \/><strong>Calderini<\/strong>: spreca l&#8217;ennesima occasione per far ricredere Cappellacci <strong>5<\/strong><br \/><strong>Alessandro<\/strong>: quando non gira lui per il Cosenza \u00e9 notte buia <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Chinellato<\/strong>: non ripete le buone prove fornite in altre partite <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Partipilo<\/strong>: non incide in nessun modo <strong>5<\/strong><br \/><strong>Mosciaro<\/strong>: gioca poco, peccato <strong>S<\/strong>.<strong>V.<\/strong><br \/><strong>Cappellacci<\/strong>: le soluzioni attuate in questa partita non sembrano per nulla azzeccate <strong>5<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il Cosenza torna da Foggia con una sconfitta che, con una partita pi\u00f9 convinta poteva essere evitata.<\/p>\n","protected":false},"author":22,"featured_media":30894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-30893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30893"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30893\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30894"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}