{"id":3095,"date":"2012-09-04T07:19:09","date_gmt":"2012-09-04T05:19:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3095"},"modified":"2023-01-17T13:35:26","modified_gmt":"2023-01-17T12:35:26","slug":"122-cinema-morto-il-gigante-nero-del-miglio-verde-con-tom-hanks","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/122-cinema-morto-il-gigante-nero-del-miglio-verde-con-tom-hanks\/","title":{"rendered":"Cinema: morto il gigante nero del Miglio Verde con Tom Hanks"},"content":{"rendered":"<p>AGI) <strong>WASHINGTON<\/strong> &#8211; E&#8217; morto a 54 anni per un infarto l&#8217;attore nero Michael Clarke Duncan. Grande caratterista, divenne celebre nel 1999 per il ruolo di &#8216;Coffey&#8217;, il condannato a morte che faceva miracoli, nel film il &#8216;Miglio verde&#8217; con Tom Hanks. Alto quasi 2 metri per 150 kg di peso Duncan<\/p>\n<p>  <!--more-->  <\/p>\n<p>era considerato dai colleghi un gigante dal cuore d&#8217;oro .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AGI) WASHINGTON &#8211; E&#8217; morto a 54 anni per un infarto l&#8217;attore nero Michael Clarke Duncan. Grande caratterista, divenne celebre nel 1999 per il ruolo di &#8216;Coffey&#8217;, il condannato a morte che faceva miracoli, nel film il &#8216;Miglio verde&#8217; con Tom Hanks. Alto quasi 2 metri per 150 kg di peso Duncan<\/p>\n","protected":false},"author":22,"featured_media":114,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,40,34,5],"tags":[],"class_list":["post-3095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-cultura-spettacolo","category-magazine","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3095"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}