{"id":30988,"date":"2014-03-06T10:10:20","date_gmt":"2014-03-06T09:10:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/munizioni-e-contraffazione-del-sigillo-parlamentare-assolto-quintieri\/"},"modified":"2023-01-17T12:50:04","modified_gmt":"2023-01-17T11:50:04","slug":"13140-munizioni-e-contraffazione-del-sigillo-parlamentare-assolto-quintieri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13140-munizioni-e-contraffazione-del-sigillo-parlamentare-assolto-quintieri\/","title":{"rendered":"Munizioni e contraffazione del sigillo parlamentare, assolto Quintieri"},"content":{"rendered":"<p>PAOLA &#8211; I fatti non sussistono. E&#8217; questo il verdetto del Tribunale di Paola sulla vicenda che ha coinvolto l&#8217;attivista radicale Emilio Quintieri.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il giovane era accusato di aver contraffatto il sigillo della Camera dei Deputati ed averlo utilizzato per redigere due interrogazioni parlamentari a nome dell\u2019Onorevole Angela Napoli, all\u2019epoca dei fatti, Deputata di Alleanza Nazionale e Vice Presidente della Commissione Parlamentare Antimafia. Questa l\u2019accusa principale che era contestata al cetrarese Emilio Quintieri, ecologista radicale ed al paolano Romeo Borgia, all\u2019epoca dei fatti, Ispettore Capo del Corpo Forestale di Cosenza. <strong>A Quintieri, inoltre, veniva contestata la detenzione abusiva di alcune munizioni mentre il Borgia era accusato di aver abusato della sua qualit\u00e0 di Ufficiale di Polizia Giudiziaria per porre sotto sequestro una discarica abusiva a Cetraro in localit\u00e0 Santa Lucia ed un terreno a San Lucido in localit\u00e0 Cerasuolo interessato da lavori di sbancamento.<\/strong> Per quanto concerne l\u2019imputazione di contraffazione del sigillo di Palazzo Montecitorio per il quale i due imputati erano stati denunciati nel 2007 dall\u2019ex Deputata Napoli era stato lo stesso Pubblico Ministero Linda Gambassi a chiedere l\u2019assoluzione alla luce della provata attivit\u00e0 di collaborazione del Quintieri con alcuni Gruppi Parlamentari sia alla Camera che al Senato. Inoltre, il Sostituto Procuratore, ha spiegato al Collegio giudicante che non era stato consumato alcun reato in quanto le \u201cinterrogazioni parlamentari\u201d incriminate non erano altro che delle bozze preparate dal Quintieri che poi venivano inviate ai membri del Parlamento per essere vagliate e presentate.<\/p>\n<p>&nbsp;<\/p>\n<p>Nel caso specifico, non erano state sottoscritte a nome dell\u2019On. Napoli e comunque solo la stessa avrebbe potuto presentarle alla Camera. In sostanza tutto ci\u00f2 che Quintieri aveva precisato nella precedente udienza del 27 novembre con dichiarazioni spontanee con le quali aveva categoricamente smentito quanto affermato in aula dall\u2019ex parlamentare. Per quanto concerne, invece, gli episodi di abuso d\u2019ufficio ascritte a Borgia il Pm aveva chiesto la condanna ad <strong>1 anno e 4 mesi ritenendo che il forestale essendo in servizio a Cosenza non poteva operare n\u00e9 a Cetraro n\u00e9 a San Lucido<\/strong> precisando che la sua attivit\u00e0 era stata posta in essere a Cetraro, in virt\u00f9 dei suoi rapporti personali con Quintieri, con l\u2019intento di denigrare il Sindaco Giuseppe Aieta impedendo al Comune la raccolta dei rifiuti creandogli danno economico e d\u2019immagine mentre a San Lucido allo scopo di danneggiare dei cittadini, parenti di un collega del Borgia con il quale non vi erano buoni rapporti. Per Quintieri, infine, aveva chiesto la condanna ad 1 mese di arresto per la detenzione abusiva di munizionamento. Il difensore degli imputati Sabrina Mannarino, si associava alla richiesta del Pm per quanto riguarda la presunta contraffazione del sigillo della Camera e, diversamente, chiedeva l\u2019assoluzione dei suoi assistiti per gli altri capi di imputazione, ritenendo quanto in fatto tanto in diritto la legittimit\u00e0 di tutto quanto posto in essere.<\/p>\n<p>&nbsp;<\/p>\n<p>Tutta l\u2019inchiesta era stata istruita dal Pubblico Ministero Eugenio Facciolla con varie perquisizioni personali e locali, sequestri, intercettazioni telefoniche ed ambientali eseguite dal personale della Polizia di Stato di Gioia Tauro e dalla Sezione di Polizia Giudiziaria del Corpo Forestale dello Stato della Procura di Paola<strong>.<\/strong> Le motivazioni che hanno portato al verdetto assolutorio saranno depositate nei prossimi 90 giorni. Finalmente, dopo 7 anni, dice Emilio Quintieri, sono state neutralizzate le accuse assurde mosse nei miei riguardi e dell\u2019Ispettore Borgia. Eravamo consapevoli che saremmo stati assolti tant\u2019\u00e8 vero che abbiamo fatto di tutto per arrivare a sentenza poich\u00e9, tra pochi mesi, tutti i reati contestati sarebbero caduti in prescrizione. Alla fine abbiamo anche prestato il nostro consenso affinch\u00e9 non venisse rinnovata l\u2019istruzione dibattimentale a causa della sostituzione della composizione iniziale del collegio giudicante. P<strong>er 7 anni mi hanno perseguito e tenuto sequestrati computer ed altro materiale arrecandomi dei danni nonostante pi\u00f9 volte avevo chiarito i fatti e chiesto il dissequestro.<\/strong> Per questi motivi, conclude Quintieri, far\u00f2 causa al Ministero della Giustizia per l\u2019irragionevole durata del processo e per tutti i danni che mi sono stati cagionati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PAOLA &#8211; I fatti non sussistono. E&#8217; questo il verdetto del Tribunale di Paola sulla vicenda che ha coinvolto l&#8217;attivista radicale Emilio Quintieri.<\/p>\n","protected":false},"author":18,"featured_media":30989,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,28],"tags":[],"class_list":["post-30988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=30988"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/30988\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/30989"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=30988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=30988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=30988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}