{"id":3124,"date":"2012-09-04T13:08:28","date_gmt":"2012-09-04T11:08:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3124"},"modified":"2023-01-17T13:35:30","modified_gmt":"2023-01-17T12:35:30","slug":"154-il-tdl-rigetta-la-richiesta-di-scarcerazione-per-il-senatore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/154-il-tdl-rigetta-la-richiesta-di-scarcerazione-per-il-senatore\/","title":{"rendered":"Margherita, Lusi resta in carcere"},"content":{"rendered":"<p style=\"text-align: justify;\">Libert\u00e0 rigettata. Resta in carcere il senatore della Margherita, Luigi Lusi. Il tribunale del Riesame ha confermato gli arresti dopo la pronuncia della Cassazione che il 31 luglio scorso aveva annullato con rinvio la conferma da parte del tribunale della libert\u00e0 della custodia nel carcere di Rebibbia.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Nel corso dell&#8217;udienza davanti al Riesame, svolta il 31 agosto scorso, i pm si erano detti favorevoli alla concessione degli arresti domiciliari per Lusi. Per i pm la misura, nel caso, sarebbe dovuta essere eseguita in un convento abruzzese. I difensori del parlamentare, gli avvocati Luca Petrucci e Renato Archidiacono, non avevano formalizzato l&#8217;istanza al giudice delle indagini preliminari in attesa della decisione del Riesame. Nei giorni successivi il gip Simonetta D&#8217;Alessandro aveva confermato la custodia cautelare in carcere<\/p>\n<p style=\"text-align: justify;\">Lusi \u00e8 in cella a Rebibbia dal 20 giugno scorso, dopo il via libera al suo arresto pronunciato dall&#8217;aula del Senato. Il senatore \u00e8 accusato, assieme ad altre persone, tra cui anche la moglie Giovanna Petricone, di associazione a delinquere finalizzata all&#8217;appropriazione indebita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Libert\u00e0 rigettata. Resta in carcere il senatore della Margherita, Luigi Lusi. Il tribunale del Riesame ha confermato gli arresti dopo la pronuncia della Cassazione che il 31 luglio scorso aveva annullato con rinvio la conferma da parte del tribunale della libert\u00e0 della custodia nel carcere di Rebibbia.<\/p>\n","protected":false},"author":22,"featured_media":172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16,5],"tags":[],"class_list":["post-3124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3124"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/172"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}