{"id":31306,"date":"2014-03-18T08:30:35","date_gmt":"2014-03-18T07:30:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-punto-sul-ventottesimo-turno-di-lega-pro-2-gir-b\/"},"modified":"2023-01-17T12:50:33","modified_gmt":"2023-01-17T11:50:33","slug":"13306-il-punto-sul-ventottesimo-turno-di-lega-pro-2-gir-b","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13306-il-punto-sul-ventottesimo-turno-di-lega-pro-2-gir-b\/","title":{"rendered":"Il punto sul ventottesimo turno di Lega Pro 2 Girone B"},"content":{"rendered":"<p>COSENZA &#8211; Il ventottesimo turno di campionato conferma come tutto sia ancora da decidere.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Partiamo dalla parte bassa della classifica, dove se si esclude il fanalino di coda <strong>Gavorrano,<\/strong> tutte le altre squadre conservano intatte le possibilit\u00e0 di salvezza. Proprio il <strong>Gavorrano<\/strong> con la sconfitta subita ad opera del <strong>Messina,<\/strong> sembra aver poche possibilit\u00e0 di recupero, visto anche il pesante ritardo nei confronti delle dirette rivali. <strong>Messina<\/strong> invece quasi salvo dopo questa vittoria e mentalmente nella posizione di poter chiudere il campionato in crescendo. Il pari fra Aversa e <strong>Arzanese<\/strong> serve a tenere accesa la speranza di salvezza delle due compagini <strong>campane,<\/strong> anche se la situazione dei <strong>napoletani<\/strong> sembra un po pi\u00f9 complessa. Potrebbe costare cara <strong>all\u2019Aprilia<\/strong> la sconfitta interna subita ad opera della <strong>Vigor Lamezia,<\/strong> scivolati con questo passo falso in una posizione di classifica pi\u00f9 che preoccupante. Da parte loro i <strong>lametini<\/strong> riescono con questo successo ad allontanarsi momentaneamente dalle posizioni pi\u00f9 scomode. Seconda trasferta e seconda vittoria consecutiva per il <strong>Sorrento,<\/strong> che dimostra ancora una volta la propensione a giocare meglio lontano dal campo amico e nello stesso tempo riesce a risalire in classifica, rilanciandosi prepotentemente per un posto nella corsa alla salvezza. Complice del recupero del <strong>Sorrento,<\/strong> un <strong>Teramo<\/strong> stanco e probabilmente scarico, che nelle ultime partite ha palesato grosse pecche fisiche e di concentrazione. Potrebbe costare cara al <strong>Martina<\/strong> la sconfitta interna patita ad opera del <strong>Melfi,<\/strong> i <strong>pugliesi<\/strong> dopo tanto rincorrere inciampano, dimostrando come non si possa sbagliare nulla quando si \u00e8 in fase di recupero, avvalorando la tesi che al primo ostacolo non superato, si torni in difficolt\u00e0. Il <strong>Castel Rigone<\/strong> sembra in caduta libera, perde nuovamente in casa ad opera <strong>dell\u2019Ischia,<\/strong> scivolando irrimediabilmente verso la retrocessione nei <strong>dilettanti.<\/strong> Vittoria in rimonta del <strong>Tuttocuio,<\/strong> che battendo il <strong>Chieti<\/strong> ritorna a sperare e nello stesso tempo inguaia gli abruzzesi che si ritrovano adesso ai margini della zona pi\u00f9 pericolosa della classifica. Non si fanno male <strong>Foggia<\/strong> e <strong>Casertana<\/strong> dividendosi la posta in palio, <strong>campani<\/strong> che con questo pareggio perdono il primo posto a favore del <strong>Cosenza,<\/strong> che con il minimo sforzo batte il modesto Poggibonsi, candidandosi come seria candidata alla vittoria finale. &nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il ventottesimo turno di campionato conferma come tutto sia ancora da decidere.<\/p>\n","protected":false},"author":22,"featured_media":31307,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-31306","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31306","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=31306"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31306\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/31307"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=31306"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=31306"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=31306"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}