{"id":31548,"date":"2014-03-26T07:40:03","date_gmt":"2014-03-26T06:40:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/annuncia-il-suicidio-su-facebook-un-contatto-legge-il-post-e-avverte-la-polizia\/"},"modified":"2023-01-17T12:51:23","modified_gmt":"2023-01-17T11:51:23","slug":"13435-annuncia-il-suicidio-su-facebook-un-contatto-legge-il-post-e-avverte-la-polizia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13435-annuncia-il-suicidio-su-facebook-un-contatto-legge-il-post-e-avverte-la-polizia\/","title":{"rendered":"Annuncia il suicidio su Facebook, un contatto legge il post e avverte la polizia"},"content":{"rendered":"<p>ROMA &#8211; Ha visto quel post di una giovane modenese, pubblicato sul diario di uno dei suoi contatti Facebook e ha chiamato la polizia postale.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Un post in bacheca, un messaggio sul suo diario in cui una ragazza annunciava di volersi togliere la vita. Un&#8217;amica per\u00f2 lo ha letto e cos\u00ec gli agenti in servizio al Compartimento di Roma, hanno immediatamente fatto scattare gli accertamenti per verificare le informazioni del profilo e valutare l&#8217;attendibilit\u00e0 del post. Localizzata la persona del profilo attraverso un suo parente i poliziotti hanno informato la Centrale Operativa della Questura di Modena che ha inviato sul luogo segnalato i poliziotti e gli operatori del 118, i quali giunti nell&#8217;abitazione, hanno trovato la donna con i polsi tagliati e sanguinanti, ma ancora viva. Dopo i primi soccorsi avvenuti \u00e8 stata trasportata in ospedale. Da una prima ricostruzione effettuata dalla polizia, l&#8217;origine del gesto sarebbe riconducibile a ragioni sentimentali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Ha visto quel post di una giovane modenese, pubblicato sul diario di uno dei suoi contatti Facebook e ha chiamato la polizia postale.<\/p>\n","protected":false},"author":19,"featured_media":31549,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-31548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=31548"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/31549"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=31548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=31548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=31548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}