{"id":31570,"date":"2014-03-26T16:28:29","date_gmt":"2014-03-26T15:28:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/pentito-bomba-alfano\/"},"modified":"2023-01-17T12:51:23","modified_gmt":"2023-01-17T11:51:23","slug":"13446-pentito-bomba-alfano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13446-pentito-bomba-alfano\/","title":{"rendered":"L&#8217;attentato ad Alfano fall\u00ec a causa dei Lo Giudice, le rivelazioni del pentito"},"content":{"rendered":"<p>CATANZARO &#8211; Cosa Nostra voleva un attentato ai danni del ministro Angelino Alfano, ma il clamore suscitato dalle bombe della &#8216;ndrangheta contro gli edifici giudiziari di Reggio Calabria compromise il progetto.<\/p>\n<p>  <!--more-->  <\/p>\n<p>E&#8217; quanto emerso nel corso del processo con rito immediato a carico di tre persone imputate per gli attentati di tre anni fa contro i magistrati in servizio nella citta&#8217; dello Stretto, e in particolare contro il procuratore generale Giuseppe Di Landro, e l&#8217;ex procuratore Giuseppe Pignatone, ora a capo della Procura di Roma, entrambi destinatari delle intimidazioni. Il dato e&#8217; fra le dichiarazioni rilasciate in aula dal pentito Luigi Rizza, sentito in particolare a proposito dei suoi rapporti con Luciano Lo Giudice &#8211; uno degli imputati &#8211; e di quanto emerso al riguardo durante la loro permanenza in carcere. Rizza ha confermato di aver appreso che i Lo Giudice avrebbero ideato e compiuto gli attentati ai danni dei magistrati reggini, suscitando l&#8217;ira di piu&#8217; di qualcuno, perche&#8217; lo avrebbero fatto decidendo &#8220;in autonomia&#8221; senza il placet di tutti i &#8220;capi famiglia&#8221;, e soprattutto della mafia siciliana che avrebbe visto compromesso il progetto di compiere l&#8217;attentato contro Alfano.<\/p>\n<p>&nbsp;<\/p>\n<p>L&#8217;udienza e&#8217; stata dedicata anche alle dichiarazioni del boss Nino Lo Giudice, in collegamento da una localita&#8217; protetta. Le sue dichiarazioni sono state costellate da moltissimi &#8220;non ricordo&#8221;, tanto rispetto alle sue iniziali deposizioni accusatorie in merito alla programmazione ed attuazione degli attentati, quanto rispetto al contenuto dei suoi oramai famosi memoriali con cui smenti&#8217; il contenuto della sua precedente collaborazione. Lo Giudice non ha in concreto negato i fatti oggetto del processo, ha confermato i lunghi interrogatori avuti con gli inquirenti in fase di indagini, ma aggiungendo di non ricordarne il contenuto. Al processo, comunque, e&#8217; stata avanzata la richiesta di tradurre in aula di persona Nino Lo Giudice, ma in merito i giudici si sono riservati di decidere dopo le opportune verifiche in merito alla garanzia del mantenimento delle condizioni di sicurezza soprattutto del pentito. Il dibattimento &#8211; nel quale sono costituiti parte civile il Ministero della Giustizia, la Regione Calabria e il Comune di Reggio Calabria &#8211; e&#8217; stato infine rinviato al prossimo 9 aprile.<\/p>\n<p>Sul banco degli imputati siedono Luciano Lo Giudice, Antonio Cortese, ritenuto l&#8217;armiere della cosca Lo Giudice, e Vincenzo Puntorieri, legato a Cortese. Ha invece scelto tempo fa la strada del giudizio abbreviato il quarto imputato, il boss Nino Lo Giudice, che e&#8217; stato condannato a 6 anni e 4 mesi di reclusione, e tempo dopo ha fatto perdere le proprie tracce per poi rifarsi vivo con un memoriale fatto recapitare al proprio difensore, con il quale ha ritrattato le proprie dichiarazioni da collaboratore. Nel corso delle indagini gli imputati sono stati raggiunti, il 15 aprile del 2012, da un&#8217;ordinanza cautelare di custodia in carcere come presunti responsabili degli attentati compiuti contro la Procura generale di Reggio e l&#8217;abitazione del procuratore generale Di Landro, nonche&#8217; delle intimidazioni di cui e&#8217; stato vittima l&#8217;ex procuratore della Repubblica in servizio nella Citta&#8217; dello Stretto, Pignatone. L&#8217;inchiesta ebbe un input determinante proprio da Antonino Lo Giudice, meglio noto come &#8220;Nino&#8221;, quando questi decise di collaborare.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Cosa Nostra voleva un attentato ai danni del ministro Angelino Alfano, ma il clamore suscitato dalle bombe della &#8216;ndrangheta contro gli edifici giudiziari di Reggio Calabria compromise il progetto.<\/p>\n","protected":false},"author":22,"featured_media":31571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-31570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=31570"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/31571"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=31570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=31570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=31570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}