{"id":31640,"date":"2014-03-28T13:17:10","date_gmt":"2014-03-28T12:17:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/il-comitato-prendocasa-occupa-una-palazzina-nel-cuore-di-cosenza\/"},"modified":"2023-01-17T12:51:27","modified_gmt":"2023-01-17T11:51:27","slug":"13483-il-comitato-prendocasa-occupa-una-palazzina-nel-cuore-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13483-il-comitato-prendocasa-occupa-una-palazzina-nel-cuore-di-cosenza\/","title":{"rendered":"Il comitato Prendocasa occupa una palazzina nel cuore di Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; Poche ore fa l\u2019ultima occupazione del comitato Prendocasa.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Lo stesso collettivo che qualche mese fa occup\u00f2 l\u2019istituto delle Canossiane su Viale della Repubblica, oggi ha deciso di \u201cappropriarsi\u201d di una palazzina nel centro di Cosenza, precisamente in Via Minzoni, tra corso Mazzini e via XXIV Maggio. Anche quest\u2019ultimo palazzo \u00e8 di propriet\u00e0 clericale ormai disabitato da circa un anno e mezzo. L\u2019occupazione di oggi, fanno sapere dal comitato Prendocasa, \u00e8 la risposta al \u201cpiano casa\u201d del Premier Renzi che, sostengono, \u201cregala l\u2019ennesima opportunit\u00e0 di profitto facile ai grandi affaristi e padroni del mattone e del cemento, n\u00e9 ha attuato nessuna seria politica di contenimento contro quella che ormai \u00e8 divenuta una vera e propria emergenza sociale, ma addirittura la preclusione per gli occupanti abusivi all\u2019allaccio delle utenze e alla richiesta di assegnazione della residenza\u201d. Sul posto si sono recati gli uomini della Questura di Cosenza che non hanno potuto fare altro che constatare l\u2019avvenuta occupazione dell\u2019istituto del Sacro Cuore del Verbo Incarnato. All&#8217;interno dello stabile hanno trovato riparo gi\u00e0 cinquanta persone, tra cui donne e bambini.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Poche ore fa l\u2019ultima occupazione del comitato Prendocasa.<\/p>\n","protected":false},"author":22,"featured_media":31641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-31640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=31640"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/31641"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=31640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=31640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=31640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}