{"id":31680,"date":"2014-03-29T14:29:53","date_gmt":"2014-03-29T13:29:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/syriza-in-calabria-contro-l-austerity\/"},"modified":"2023-01-17T12:51:29","modified_gmt":"2023-01-17T11:51:29","slug":"13504-syriza-in-calabria-contro-l-austerity","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13504-syriza-in-calabria-contro-l-austerity\/","title":{"rendered":"Elezioni europee, Syriza in Calabria con il suo programma &#8216;anti-banchieri&#8217;"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; &#8220;L\u2019Europa di oggi \u00e8 ingiusta e produce diseguaglianza e povert\u00e0. Bisogna invertire la rotta lavorando per un\u2019Europa dei diritti e della solidariet\u00e0&#8221;.&nbsp;<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il leader greco del partito Syriza spiega il progetto di costruzione di un&#8217;Europa fuori dall&#8217;austerity. Il Consiglio regionale della Calabria, in un aula gremita di simpatizzanti, ha ospitato la presentazione della lista &#8216;L\u2019Altra Europa con Tsipras&#8217;. All\u2019incontro ha partecipato Argyris Panagopoulos, giornalista e portavoce in Italia di Alexis Tsipras e di <strong>Syriza, il partito che in pochi anni \u00e8 diventata la prima forza della Grecia, che oggi guida in Europa il fronte contro le politiche di austerity.<\/strong> I due candidati calabresi nella lista saranno Tonino Perna e Domenico Gattuso. Gattuso, esperto di trasporti, si \u00e8 soffermato molto nel suo intervento sul fatto che i soldi in questo settore vengono spesi solo nel nord Europa lasciando tutto il sud e le aree interne abbandonate. Ha ricordato anche che<strong> in Calabria i fondi europei non vengono spesi come si dovrebbe <\/strong>e c\u2019\u00e8 il rischio di un disimpegno degli stessi da parte di Bruxelles. <strong>Sull\u2019Europa ha sottolineato che bisogna \u201cliberarla dalle lobby finanziarie e riconsegnarla ai cittadini\u201d. <\/strong>Tonino Perna, docente di sociologia economica e assessore al Comune di Messina, ha rimarcato invece <strong>il concetto secondo cui il debito, nei paesi della periferia, non \u00e8 pi\u00f9 ripagabile e che bisogna annullarlo in tutto o in parte, pena l\u2019essere strangolati<\/strong> dall\u2019austerity. \u201cC\u2019\u00e8 poi un debito ecologico e un debito sociale \u2013 ha ricordato &#8211; , nei confronti dell\u2019ambiente e delle nuove generazioni. L\u2019Europa che abbiamo davanti non \u00e8 quella che hanno sognato i suoi padri, n\u00e9 quella che hanno apprezzato i cittadini provenienti da altre parti del mondo. L\u2019Europa di oggi \u00e8 ingiusta e produce diseguaglianza e povert\u00e0. Bisogna invertire la rotta, allora, lavorando per un\u2019Europa dei diritti e della solidariet\u00e0\u201d. Un incoraggiamento per una lista che mira a costruire in Italia una nuova soggettivit\u00e0 della sinistra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; &#8220;L\u2019Europa di oggi \u00e8 ingiusta e produce diseguaglianza e povert\u00e0. Bisogna invertire la rotta lavorando per un\u2019Europa dei diritti e della solidariet\u00e0&#8221;.&nbsp;<\/p>\n","protected":false},"author":18,"featured_media":31681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-31680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=31680"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/31681"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=31680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=31680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=31680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}