{"id":31803,"date":"2014-04-03T04:11:18","date_gmt":"2014-04-03T02:11:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/evasione-fiscale-per-4-anni-sequestrati-beni-di-una-societa-navale\/"},"modified":"2023-01-17T12:51:37","modified_gmt":"2023-01-17T11:51:37","slug":"13565-evasione-fiscale-per-4-anni-sequestrati-beni-di-una-societa-navale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13565-evasione-fiscale-per-4-anni-sequestrati-beni-di-una-societa-navale\/","title":{"rendered":"Evasione fiscale per 4 anni, sequestrati beni di una societ\u00e0 navale"},"content":{"rendered":"<p>TROPEA (VV) &#8211; Sigilli ad automobili, immobili e conti correnti.<\/p>\n<p>  <!--more-->  <\/p>\n<p>In totale beni per 2 milioni di euro sono stati sequestrati dai finanzieri del Nucleo di polizia tributaria di Vibo Valentia all&#8217;amministratore unico di una societ\u00e0 di Pizzo Calabro operante nel settore del rimessaggio e della cantieristica navale. I finanzieri hanno recuperato a tassazione, per il periodo 2009-2013, imposte sui redditi per oltre 3 milioni e oltre 200 mila euro di Iva. Il legale rappresentante \u00e8 stato denunciato per dichiarazione infedele e omessa dichiarazione. I decreti di sequestro preventivo sono stati emessi dal Tribunale di Vibo. L&#8217;attivit\u00e0 trae origine da una precedente verifica fiscale ai fini delle imposte dirette e dell&#8217;Iva a conclusione della quale sono state accertate numerose violazioni di carattere amministrativo e penale. Le indagini hanno portato gli investigatori ad acquisire elementi di prova tali da indurre il gip ad emettere i decreti di sequestro preventivo finalizzati alla confisca anche con formula per equivalente sui beni nella disponibilit\u00e0 dell&#8217;indagato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TROPEA (VV) &#8211; Sigilli ad automobili, immobili e conti correnti.<\/p>\n","protected":false},"author":19,"featured_media":31804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-31803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=31803"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/31803\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/31804"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=31803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=31803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=31803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}