{"id":32054,"date":"2014-04-10T09:21:56","date_gmt":"2014-04-10T07:21:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/omicidio-yara-gambirasio-l-assassino-e-il-figlio-illegittimo-dell-autista-morto\/"},"modified":"2023-01-17T12:52:01","modified_gmt":"2023-01-17T11:52:01","slug":"13698-omicidio-yara-gambirasio-l-assassino-e-il-figlio-illegittimo-dell-autista-morto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13698-omicidio-yara-gambirasio-l-assassino-e-il-figlio-illegittimo-dell-autista-morto\/","title":{"rendered":"Omicidio Yara Gambirasio, l&#8217;assassino \u00e8 il figlio &#8216;illegittimo&#8217; dell&#8217;autista morto"},"content":{"rendered":"<p>BREMBATE DI SOPRA (BG) &#8211; Fino ad oggi c&#8217;erano stati diversi dubbi ma le risultanze investigative non lasciano dubbi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Giuseppe Guerinoni, l\u2019autista di Gorno morto nel 1999 a 61 anni e il cui corpo era stato riesumato il 7 marzo 2013, \u00e8 il padre biologico di \u00abIgnoto 1\u00bb, ovvero l&#8217;assassino della 13enne Yara Gambirasio, scomparsa il 26 novembre 2010 dopo essere uscita dal centro sportivo del paese e il cui cadavere fu rinvenuto dopo tre mesi, il 26 febbraio 2011, in un campo incolto di Chignolo d\u2019Isola. Il 99,99999987% \u00e8 la percentuale secondo la quale Guerinoni, sia il padre dell&#8217;assassino. La conferma \u00e8 arrivata dall&#8217;esame di materiale biologico prelevato dal femore della salma, esumata nel marzo dello scorso anno. L&#8217;omicida si era ferito con un coltellino durante l&#8217;aggressione ed il risultato, che fuga ogni dubbio sulla validit\u00e0 degli accertamenti precedenti, \u00e8 stato ottenuto con il raffronto eseguito dall&#8217;anatomopatologa Cristina Cattaneo, e consegnato nei giorni scorsi al pm bergamasco Letizia Ruggeri, titolare dell&#8217;inchiesta sull&#8217;omicidio di Yara. L&#8217;uomo che ha ucciso Yara dunque, \u00e8 davvero il figlio illegittimo dell&#8217;autista, ma il problema ora \u00e8 quello di rintracciare la madre. Da alcuni interrogatori agli ex colleghi dell&#8217;autista, \u00e8 emerso che l&#8217;uomo a met\u00e0 degli anni &#8217;60 avrebbe avuto una relazione extraconiugale con una donna della Val Seriana, ma al momento non si \u00e8 riusciti a risalire alla sua identit\u00e0.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BREMBATE DI SOPRA (BG) &#8211; Fino ad oggi c&#8217;erano stati diversi dubbi ma le risultanze investigative non lasciano dubbi.<\/p>\n","protected":false},"author":19,"featured_media":32055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-32054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32054"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32055"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}