{"id":3206,"date":"2012-09-06T05:26:05","date_gmt":"2012-09-06T03:26:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3206"},"modified":"2023-01-17T13:35:38","modified_gmt":"2023-01-17T12:35:38","slug":"239-accordo-tra-de-tommaso-e-aziende-friuli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/239-accordo-tra-de-tommaso-e-aziende-friuli\/","title":{"rendered":"Accordo tra De Tommaso e aziende Friuli"},"content":{"rendered":"<p>(ANSA) &#8211;<strong> CATANZARO<\/strong> &#8211; La societa&#8217; di calzature cucite a mano De Tommaso si accinge a consolidare il brand in Italia e in Europa e punta su un&#8217;ulteriore espansione in Cina, Giappone, Russia e America, andando ad aggredire anche i mercati emergenti come la Corea e i paesi arabi.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Questa strategia verr\u00e0 realizzata grazie all&#8217;importante contributo di due partner friulani, le societ\u00e0 Altea e Alba94 con sede a Codroipo (Udine). Cosimo De Tommaso si dice soddisfatto per questa nuova sfida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ANSA) &#8211; CATANZARO &#8211; La societa&#8217; di calzature cucite a mano De Tommaso si accinge a consolidare il brand in Italia e in Europa e punta su un&#8217;ulteriore espansione in Cina, Giappone, Russia e America, andando ad aggredire anche i mercati emergenti come la Corea e i paesi arabi.<\/p>\n","protected":false},"author":22,"featured_media":336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-3206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3206"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3206\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/336"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}