{"id":32062,"date":"2014-04-10T11:39:06","date_gmt":"2014-04-10T09:39:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/prete-stupro-i-ragazzini-e-poi-spari-la-curia-di-crotone-sara-parte-civile\/"},"modified":"2023-01-17T12:52:02","modified_gmt":"2023-01-17T11:52:02","slug":"13702-prete-stupro-i-ragazzini-e-poi-spari-la-curia-di-crotone-sara-parte-civile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13702-prete-stupro-i-ragazzini-e-poi-spari-la-curia-di-crotone-sara-parte-civile\/","title":{"rendered":"Prete stupr\u00f2 i ragazzini e poi spar\u00ec, la curia di Crotone sar\u00e0 parte civile"},"content":{"rendered":"<p>CROTONE &#8211; Nel processo a don Roberto Mastro parroco di Belcastro dal 2007 al 2010 la curia arcivescovile di Crotone &#8211; Santa Severina si costituir\u00e0 parte civile.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Il parroco accusato di pedofilia da diciassette ragazzini della piccola comunit\u00e0 montana era stato n<span>ominato proprio dall&#8217;arcivescovo della stessa Diocesi di Crotone Santa Severina, Domenico Graziani che nonostante la gravit\u00e0 dei fatti sino ad ogggi si era trincerato in un imbarazzante silenzio. Le uniche dichiarazioni in merito in questi anni avrebbero solo deposto in difesa del presbitero che, secondo la curia, aveva svolto il suo mandato con impegno.<\/span> La richiesta \u00e8 stata annunciata nell&#8217;udienza preliminare che poi \u00e8 slittata al prossimo settembre per errori di notifica. La Procura di Catanzaro, le settimane scorse aveva chiesto il rinvio a giudizio del sacerdote. Le indagini che hanno scosso il piccolo comune del catanzarese con meno di mille abitanti, sono scaturite dagli esposti presentati dai genitori di un bimbo che hanno segnalato alle autorit\u00e0 le violenze che pare il sacerdote abbia commesso ai danni del figlio. La denuncia avrebbe cos\u00ec scatenato una vera e propria bomba nei confronti del parroco con decine di denunce da parte di altre famiglie cui ragazzini hanno confessato di essere stati oggetto di particolari attenzioni da parte del sacerdote. Le indagini sono durate oltre tre anni, seguite da un pool di esperti che ha ritenuto attendibili tutti i racconti dei minori. Depositate le denunce il prete accusato di pedofilia spar\u00ec nel nulla in tutta fretta e pare oggi si trovi in una localit\u00e0 del centro Italia. I ragazzini interrogati dalle autorit\u00e0 hanno<span> tutti confermato di aver avuto &#8220;rapporti di natura sessuale&#8221; con il parroco che nella piccola parrocchia di Belcastro aveva fondato anche un gruppo scout per adescare i giovani.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Nel processo a don Roberto Mastro parroco di Belcastro dal 2007 al 2010 la curia arcivescovile di Crotone &#8211; Santa Severina si costituir\u00e0 parte civile.<\/p>\n","protected":false},"author":18,"featured_media":32063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32062"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32063"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}