{"id":32102,"date":"2014-04-11T12:05:09","date_gmt":"2014-04-11T10:05:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/jfjfd\/"},"modified":"2023-01-17T12:52:04","modified_gmt":"2023-01-17T11:52:04","slug":"13722-jfjfd","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13722-jfjfd\/","title":{"rendered":"La &#8216;ndrangheta nei supermercati, Sma si difende: &#8220;Volevamo dare lavoro&#8221;"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Sma, Simply e Spaccio Alimentare. Sono 11 i supermercati a cui l&#8217;antimafia ha ieri apposto i sigilli.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Si tratta degli esercizi commerciali sequestrati nel corso del maxi sequestro eseguito ai danni degli imprenditori Domenico Giovanni &#8220;Dominique&#8221; Suraci e Giuseppe Croc\u00e8. La direzione della nota catena di supermercati Sma Spa intende precisare che gli stabilimenti sottoposti a sequestro &#8220;sono gi\u00e0 da luglio 2012 gestiti da un pool di amministratori giudiziari nominati dalla Procura di Reggio, con i quali <strong>Sma ha continuato a collaborare, in forza dei menzionati contratti di franchising, per il mantenimento in esercizio dei punti vendita anche al fine di tutelare i dipendenti degli esercizi commerciali coinvolti<\/strong>. Detti provvedimenti di sequestro si ricollegano alle operazioni Sistema e Assenzio condotte dalla Procura di Reggio in collaborazione con la competente Dia, nell&#8217;ambito delle quali, gi\u00e0 nel luglio 2012, si era provveduto all&#8217;esecuzione di numerosi provvedimenti cautelari personali nei confronti di svariati soggetti, nonch\u00e9 il<strong> congelamento delle quote societarie e del patrimonio aziendale delle realt\u00e0 commerciali a tali soggetti facenti capo<\/strong>. Sma ha stipulato in passato alcuni contratti di franchising con le societ\u00e0 Sgs Group srl e Saldo srl, societ\u00e0 riconducibili, rispettivamente, a Croc\u00e8 e Suraci, soggetti coinvolti nelle operazioni, cos\u00ec concedendo a tali aziende di distribuire i propri prodotti nei rispettivi punti vendita, utilizzando il marchio &#8216;Simply Market&#8217; e &#8216;Punto SMA&#8217;. Nel ribadire la propria assoluta estraneit\u00e0 ai fatti illeciti contestati ai soggetti indicati &#8211; conclude la nota &#8211; Sma precisa altres\u00ec di avere da tempo conferito mandato al proprio legale di fiducia, Daniele Ripamonti, al fine di tenere i contatti con l&#8217;autorit\u00e0 giudiziaria e prestare la massima collaborazione nella ricostruzione dei fatti, cos\u00ec confermando l&#8217;impegno del Gruppo nell&#8217;informare la propria attivit\u00e0 a principi di legalit\u00e0 e trasparenza&#8221;.<br \/>&nbsp;<br \/>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Sma, Simply e Spaccio Alimentare. Sono 11 i supermercati a cui l&#8217;antimafia ha ieri apposto i sigilli.<\/p>\n","protected":false},"author":18,"featured_media":32103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32102"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32103"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}