{"id":32152,"date":"2014-04-14T06:05:07","date_gmt":"2014-04-14T04:05:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/le-pagelle-di-cosenza-aprilia\/"},"modified":"2023-01-17T12:52:07","modified_gmt":"2023-01-17T11:52:07","slug":"13749-le-pagelle-di-cosenza-aprilia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13749-le-pagelle-di-cosenza-aprilia\/","title":{"rendered":"Le pagelle di Cosenza-Aprilia"},"content":{"rendered":"<p>COSENZA &#8211; Aprilia indigesta per il Cosenza, difatti la squadra laziale \u00e9 l&#8217;unica a non aver lasciato al Cosenza nemmeno un punto.<\/p>\n<p>  <!--more-->  <\/p>\n<p><strong>Orlandi<\/strong>: chiamato in causa per la prima volta nel campionato dimostra di avere qualit\u00e0 e doti di grande professionista, si disimpegna con grande sicurezza, peccato per l&#8217;espulsione <strong>6<\/strong><br \/><strong>Blondett<\/strong>: soffre nel primo tempo le discese di Montella, a sua scusante l&#8217;infortunio di domenica scorsa ad Ischia non ancora assorbito <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Bigoni<\/strong>: \u00e9 l&#8217;ultimo ad arrendersi, nel secondo tempo viene spostato a destra per tamponare le sortite degli esterni laziali <strong>6<\/strong><br \/><strong>Asante<\/strong>: bravo in fase di copertura, discreto nella fase di costruzione forse il migliore della squadra rosso blu <strong>6<\/strong><br \/><strong>Pepe<\/strong>: nel complesso una partita senza particolari sbavature, anche se in qualche circostanza \u00e8 parso poco reattivo <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Guidi<\/strong>: come il suo compagno di reparto non mostra grande concentrazione <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Corsi<\/strong>: davanti alla sua ex squadra palesa qualche incertezza di troppo <strong>5<\/strong><br \/><strong>Giordano<\/strong>: non la sua migliore partita <strong>5<\/strong><br \/><strong>Mosciaro<\/strong>: tanto impegno, ma come i suoi compagni di squadra accusa le difficolt\u00e0 di un campionato lungo e logorante <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Calderini<\/strong>: fuori dalla partita per tutti i novanta minuti <strong>5<\/strong><br \/><strong>Alessandro<\/strong>: corre e lotta ma la benzina \u00e9 finita <strong>5<\/strong>.<strong>5<\/strong><br \/><strong>Partipilo<\/strong>: non riesce ad incidere <strong>S<\/strong>.<strong>V.<\/strong><br \/><strong>Chinellato<\/strong>: non poteva essere lui a cambiare l&#8217;inerzia della gara <strong>S<\/strong>.<strong>V<\/strong>.<br \/><strong>Napolano<\/strong>: <strong>S<\/strong>.<strong>V<\/strong>.<br \/><strong>Ianni<\/strong>: esordio amaro per il secondo di Cappellacci, non proprio fortunato <strong>S<\/strong>.<strong>V.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Aprilia indigesta per il Cosenza, difatti la squadra laziale \u00e9 l&#8217;unica a non aver lasciato al Cosenza nemmeno un punto.<\/p>\n","protected":false},"author":22,"featured_media":32153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-32152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32152"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32152\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32153"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}