{"id":32160,"date":"2014-04-14T07:14:23","date_gmt":"2014-04-14T05:14:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/tama-e-il-primo-gatto-al-mondo-che-fa-il-capostazione\/"},"modified":"2023-01-17T12:52:07","modified_gmt":"2023-01-17T11:52:07","slug":"13753-tama-e-il-primo-gatto-al-mondo-che-fa-il-capostazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13753-tama-e-il-primo-gatto-al-mondo-che-fa-il-capostazione\/","title":{"rendered":"Tama, \u00e8 il primo gatto al mondo che&#8230; fa il capostazione"},"content":{"rendered":"<p>WAKAYAMA (Giappone) \u2013 Si chiama Tama, ed \u00e8 il primo gatto &#8211; capostazione in Giappone.<\/p>\n<p>  <!--more-->  <\/p>\n<p>La Kishi Station di Wakayama, regione meridionale del Giappone, \u00e8 rinomata per l\u2019architettura a forma di gatto ,a ora lo sar\u00e0 ancora di pi\u00f9 perch\u00e8 a controllore c&#8217;\u00e8 Tama, un felino diventato mascotte del luogo. Un impiegato decisamente fuori dal comune, Tama, un gatto calico, specie domestica dal caratteristico manto a mosaico. Nato a Wakayama, ha vissuto da randagio assieme ad altri gatti nei pressi della stazione. Il branco di felini ha sempre ricevuto cibo occasionale dai passeggeri e talvolta dal manager della stazione. Fino a quando nel 2004 la struttura cess\u00f2 l\u2019attivit\u00e0 per problemi finanziari. Il manager continu\u00f2 ad occuparsi ugualmente di Tama dei suoi amici. Dopo diverso tempo, quando la stazione fu riaperta su richiesta dei cittadini del posto, l\u2019azienda ferroviaria decise per\u00f2 che si doveva risparmiare molto sulle spese e cos\u00ec nel 2006 vennero selezionati diversi impiegati. I funzionari riuniti decisero di riservare un incarico speciale anche a Tama: il fortunato felino \u00e8 d\u2019allora riconosciuto ufficialmente come controllore alla Kishi Station, cui la prima occupazione \u00e8 l\u2019accoglienza dei passeggeri. Una presenza quella di Tama che potrebbe anche essere una sorta di trovata pubblicitarie per favorire l\u2019utilizzo dei mezzi pubblici, ma dal canto suo almeno il simpatico felino \u00e8 curato, coccolato e servito e ha trovato in una stazione ferroviaria la sua casa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WAKAYAMA (Giappone) \u2013 Si chiama Tama, ed \u00e8 il primo gatto &#8211; capostazione in Giappone.<\/p>\n","protected":false},"author":19,"featured_media":32161,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,22],"tags":[],"class_list":["post-32160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32160"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32161"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}