{"id":32182,"date":"2014-04-14T13:29:01","date_gmt":"2014-04-14T11:29:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/parrucchiere-sepolto-vivo-chiesti-due-ergastoli-in-appello\/"},"modified":"2023-01-17T12:52:09","modified_gmt":"2023-01-17T11:52:09","slug":"13764-parrucchiere-sepolto-vivo-chiesti-due-ergastoli-in-appello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13764-parrucchiere-sepolto-vivo-chiesti-due-ergastoli-in-appello\/","title":{"rendered":"Parrucchiere sepolto vivo chiesti due ergastoli in appello"},"content":{"rendered":"<p>CATANZARO &#8211; Un eclatante caso diu lupara bianca.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Due condanne all&#8217;ergastolo ed una a 24 anni sono state chieste dal sostituto procuratore generale Salvatore Curcio al termine della requisitoria nel processo per l&#8217;omicidio di Placido Scaramozzino, il parrucchiere ucciso il 28 settembre del 1993 ed il cui corpo non \u00e8 stato mai trovato. La richiesta di condanna \u00e8 stata avanzata ai giudici della Corte d&#8217;assise d&#8217;appello di Catanzaro dinanzi ai quali \u00e8 in corso il processo di secondo grado. I tre imputati sono Antonio Altamura, 66 anni, ritenuto il capo della cosca della &#8216;ndrangheta della frazione Ariola di Gerocarne; Vincenzo Taverniti, 53 anni, di Stilo e Antonio Gallace, 47 anni. L&#8217;accusa ha chiesto la condanna all&#8217;ergastolo per Altamura e Taverniti e Gallace alla pena di 24 anni. La sentenza di primo grado era stata emessa nell&#8217;aprile dello scorso anno ed aveva visto la condanna per l&#8217;omicidio di Altamura e Taverniti e l&#8217;assoluzione di Gallace. I tre imputati furono identificati grazie alle dichiarazioni di un minorenne coinvolto nel delitto e che successivamente ha deciso di collaborare con la giustizia. E proprio attraverso le dichiarazioni del pentito la Dda di Catanzaro ha fatto luce sull&#8217;omicidio che, secondo l&#8217;accusa, sarebbe rientrato nella logica di sterminio del gruppo Maiolo per favorire l&#8217;ascesa della cosca di &#8216;ndrangheta dei Loielo. Scaramozzino rimase vittima della lupara bianca il 28 settembre del 1993 quando gli esponenti della cosca Loielo individuarono la vittima nei pressi dell&#8217;abitazione di Maiolo. Il parrucchiere fu legato e trascinato lungo un sentiero nella boscaglia di Gerocarne. Successivamente fu colpito con una zappa al petto e alla testa. Placido Scaramozzino fu poi sepolto vivo ed il suo corpo non e&#8217; mai stato trovato. Il processo d&#8217;appello \u00e8 stato aggiornato al 10 giugno prossimo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Un eclatante caso diu lupara bianca.<\/p>\n","protected":false},"author":22,"featured_media":32183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32182"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32183"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}