{"id":3224,"date":"2012-09-06T07:31:48","date_gmt":"2012-09-06T05:31:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=3224"},"modified":"2023-01-17T13:35:40","modified_gmt":"2023-01-17T12:35:40","slug":"258-calabria-regione-vince-premio-urbanpromo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/258-calabria-regione-vince-premio-urbanpromo\/","title":{"rendered":"Calabria: Regione vince premio Urbanpromo"},"content":{"rendered":"<p>(ASCA) &#8211; CATANZARO &#8211; Il Progetto di Rigenerazione e riqualificazione delle aree urbane: strategie sostenibili per i territori calabresi della Regione Calabria &#8211; Assessorato Urbanistica e Governo del Territorio presentato alla rassegna di urbanistica nazionale URBANPROMO 2011<\/p>\n<p>  <!--more-->  <\/p>\n<p>e&#8217; risultato primo classificato del Premio Urbanistica 2012 &#8211; sezione Qualita&#8217; delle infrastrutture e degli spazi pubblici. La notizia e&#8217; giunta nella mattinata di ieri con la comunicazione ufficiale da parte della rivista &#8221;Urbanistica&#8221; e dell&#8217; INU &#8211; Istituto Nazionale di Urbanistica, che ha assegnato il premio sulla base delle preferenze espresse dai visitatori alla Mostra di Urbanpromo 2011.<\/p>\n<p>La Regione presente all&#8217;edizione 2011 della rassegna &#8221;Urban Promo&#8221;, svoltasi a Bologna sul tema prioritario della Rigenerazione Urbana, era rappresentata dall&#8217;Assessore all&#8217;Urbanistica On. Pietro Aiello, dal Direttore Generale del Dipartimento Urbanistica Arch. Saverio Putorti&#8217;, dai Dirigenti e funzionari del Dipartimento che hanno illustrato alcune tra le principali attivita&#8217; inerenti la rigenerazione urbana quale elemento per la qualita&#8217; architettonica e la pianificazione territoriale integrata nella regione oltre al &#8221;Masterplan per lo sviluppo della Portualita&#8217; Calabrese&#8221;, ed al Protocollo d&#8217;Intesa con il CNR per lo &#8221;Sviluppo della rete dei Poli di Innovazione e di Ricerca Calabresi&#8221; che prevede azioni integrate di sviluppo sostenibile per l&#8217;innovazione e la rigenerazione delle aree urbane.<\/p>\n<p>Complessivamente sono stati particolarmente apprezzati per la sperimentazione strategica sul tema dell&#8217;integrazione tra le politiche di sviluppo urbane e del territorio e le politiche di sviluppo del turismo sostenibile, meritando la proposta tra i progetti per l&#8217;assegnazione del premio &#8221;Urban Promo 2011&#8221; per l&#8217;innovazione nella pianificazione Urbanistica e Territoriale e suscitando grande interesse presso esperti e amministratori nazionali e internazionali.<\/p>\n<p>L&#8217;Assessore all&#8217;Urbanistica e Governo del Territorio, Pietro Aiello, ed il Dirigente Generale Saverio Putorti&#8217; hanno espresso soddisfazione &#8221;per il riconoscimento concesso alle esperienze urbanistiche regionali, fondate sulla forte integrazione tra le strategie di pianificazione urbanistica e territoriale e le grandi scelte dello sviluppo sociale ed economico fondato sulla competitivita&#8217; dei territori, nell&#8217;ottica del grande progetto di innovazione e di sviluppo della Calabria insito nel programma del Presidente Scopelliti&#8221;.<\/p>\n<p>La cerimonia di premiazione avra&#8217; luogo nel corso di Urbanpromo 2012 che si terra&#8217; a Bologna, nelle sedi di Palazzo D&#8217;Accursio e Sala Borsa &#8211; Urbancenter, dal 7 al 10 novembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ASCA) &#8211; CATANZARO &#8211; Il Progetto di Rigenerazione e riqualificazione delle aree urbane: strategie sostenibili per i territori calabresi della Regione Calabria &#8211; Assessorato Urbanistica e Governo del Territorio presentato alla rassegna di urbanistica nazionale URBANPROMO 2011<\/p>\n","protected":false},"author":22,"featured_media":372,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18,5],"tags":[],"class_list":["post-3224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni","category-old"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=3224"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/3224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/372"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=3224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=3224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=3224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}