{"id":32265,"date":"2014-04-17T05:02:45","date_gmt":"2014-04-17T03:02:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/pasqua-di-sopravvivenza-l-agnello-dice-grazie-e-l-uomo-vaffanculo\/"},"modified":"2023-01-17T12:52:15","modified_gmt":"2023-01-17T11:52:15","slug":"13807-pasqua-di-sopravvivenza-l-agnello-dice-grazie-e-l-uomo-vaffanculo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13807-pasqua-di-sopravvivenza-l-agnello-dice-grazie-e-l-uomo-vaffanculo\/","title":{"rendered":"Pasqua di sopravvivenza: l&#8217;agnello dice grazie e l&#8217;uomo vaffanculo"},"content":{"rendered":"<p>\u201cBuona Pasqua\u201d dice il maiale all\u2019agnello e questi, naturalmente risponde: \u201cma vaffanculo\u201d.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Parafrasando il \u201ctesto\u201d, oggi vi voglio partecipare le \u201cpreoccupazioni\u201d di circa 30mila lavoratori calabresi in mobilit\u00e0 da 9 mesi che, alla vigilia di Pasqua, non hanno percepito ancora nemmeno un centesimo.<strong> Buona Pasqua<\/strong>. Ma chi \u00e8 in \u201cforza\u201d a quest\u2019esercito in mobilit\u00e0? Che cos\u2019\u00e8 la mobilit\u00e0? I chiarimenti e le \u201crisposte\u201d li troviamo sul sito dell\u2019inps: \u201c\u00c8 un intervento a sostegno di particolari categorie di lavoratori licenziati da aziende in difficolt\u00e0 che garantisce al lavoratore un\u2019indennit\u00e0 sostitutiva della retribuzione e ne favorisce il reinserimento nel mondo del lavoro\u201d. Allora la mobilit\u00e0 dovrebbe garantire \u201cparticolari categorie di lavoratori licenziati\u201d e \u201cgarantire un\u2019indennit\u00e0 sostitutiva della retribuzione\u201d. A me pare tale e quale l\u2019enunciazione dell\u2019articolo 1 della costituzione: \u201cL&#8217;Italia \u00e8 una Repubblica democratica, fondata sul lavoro\u201d. A questi si aggiungono lavoratori non pagati e sottopagati, in cerca di occupazione. Bhe <strong>Buona Pasqua<\/strong> a quest\u2019esercito che \u201cingrossa\u201d ma non \u201cingrassa\u201d. Le colpe: ognuno rimpalla, del resto come al solito. Dal Governo alle Regione, dalle Regioni al Governo e poi all\u2019inps e via dicendo. Ancora <strong>Buona Pasqua<\/strong> anche a chi andr\u00e0 a votare alle prossime elezioni europee a quei politici \u201cesodati\u201d si, ma dalla giustizia \u201citaliana\u201d che non punisce. A questo, punto fatemi tranquillizzare l\u2019Agnellino perch\u00e9 per lui sar\u00e0 veramente un <strong>Buona Pasqua<\/strong> visto che non ci sono nemmeno i soldi per \u201ccomprarlo\u201d. Cos\u00ec la risposta resta a noi che continuiamo ad essere \u201ccomprabili\u201d: a tutti quei politici e politicanti, mestieranti della politica e portaborse, ignoranti \u201cacculturati\u201d che ci augurano <strong>Buona Pasqua<\/strong>, rispondiamo in coro \u201c<strong>ma Vaffanculo<\/strong>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cBuona Pasqua\u201d dice il maiale all\u2019agnello e questi, naturalmente risponde: \u201cma vaffanculo\u201d.<\/p>\n","protected":false},"author":22,"featured_media":32266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-32265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32265"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32266"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}