{"id":32269,"date":"2014-04-17T05:58:31","date_gmt":"2014-04-17T03:58:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/omicidi-sena-e-bella-bella-inflitti-quattro-ergastoli-per-la-morte-dei-boss\/"},"modified":"2023-01-17T12:52:15","modified_gmt":"2023-01-17T11:52:15","slug":"13809-omicidi-sena-e-bella-bella-inflitti-quattro-ergastoli-per-la-morte-dei-boss","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13809-omicidi-sena-e-bella-bella-inflitti-quattro-ergastoli-per-la-morte-dei-boss\/","title":{"rendered":"Omicidi Sena e Bella bella, inflitti quattro ergastoli per la morte dei boss"},"content":{"rendered":"<p>COSENZA &#8211; Due morti eccellenti avvenute tra il 1999 e il 2000.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Si tratta dell&#8217;omicidio del boss Antonio Sena ucciso a Castrolibero e del suo vecchio amico Francesco Bruni. Ieri in Corte d&#8217;assise \u00e8 stata pronunciata la sentenza di condanna in primo grado degli imputati ritenuti autori dei due delitti. Fine pena mai per Ettore Lanzino identificato come il mandante dei due omicidi e per il presunto esecutore Franco Presta. Nella ricostruzione dei fatti che insanguinarono Cosenza tra il &#8217;99 e il 2001 per il riassetto del potere delle cosche sul territorio bruzio rientra anche l&#8217;uccisione di Primiano Chiarello affiliato al gruppo Bruni. Nicola Acri di Rossano e Franco Abbruzzese di Cassano allo Jonio sono stati anch&#8217;essi condannati ieri all&#8217;ergastolo con l&#8217;accusa di aver ucciso materialmelmente il giovane rapinatore arruolato tra le fila di Bella bella. Quattordici e dodici anni di reclusione sono invece stati comminati rispettivamente ai due collaboratori di giustizia Vincenzo Dedato ex autista di Tonino Sena e Francesco &#8216;Mafarda&#8217; Bevilacqua. Quest&#8217;ultimo nel corso delle proprie deposizioni in merito all&#8217;esecuzione del &#8216;soldato&#8217; Chiarello dichiar\u00f2: &#8220;lo afferrai per i capelli e iniziai a tagliargli la testa, ma l&#8217;accetta era troppo piccola&#8221;. Un dettaglio della cruenza che segn\u00f2 l&#8217;inizio di quella che la magistratura ha ormai definito la terza guerra di mafia a Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Due morti eccellenti avvenute tra il 1999 e il 2000.<\/p>\n","protected":false},"author":18,"featured_media":32270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-32269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32269"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32270"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}