{"id":32271,"date":"2014-04-17T06:12:39","date_gmt":"2014-04-17T04:12:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/donne-segregate-e-ridotte-in-schiavitu-arrestato-39enne\/"},"modified":"2023-01-17T12:52:15","modified_gmt":"2023-01-17T11:52:15","slug":"13810-donne-segregate-e-ridotte-in-schiavitu-arrestato-39enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13810-donne-segregate-e-ridotte-in-schiavitu-arrestato-39enne\/","title":{"rendered":"Madre e figlia segregate e ridotte in schiavit\u00f9, arrestato 39enne"},"content":{"rendered":"<p>REGGIO CALABRIA &#8211; Aveva ridotto due donne in schiavit\u00f9 e alla fame.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Vittime, madre e figlia, che erano state private di tutto e costrette addirittura a consegnare all&#8217;uomo la pensione. Le donne erano tenute segregate in casa, e gli veniva impedito di condurre di una vita normale, persino di guardare la tv. Massimo Idone, di 39 anni, \u00e8 stato arrestato dai carabinieri a Reggio Calabria con l&#8217;accusa di riduzione in schiavit\u00f9 e atti persecutori. Idone aveva allacciato una relazione con la ragazza finendo per soggiogare entrambe le donne segregate nella loro abitazione, costrette non solo senza cibo, ma private anche delle cure mediche. Tutto sarebbe iniziato nell&#8217;ottobre scorso quando i carabinieri sono venuti al corrente delle condizioni di segregazione e miseria in cui le due donne vivevano. I militari si sarebbero persino appostati davanti all&#8217;ufficio postale dove la donna, vedova, incassava la pensione di reversibilit\u00e0 del marito constatando che Idone il comportamento dell&#8217;uomo che l&#8217;aspettava fuori e dopo essersi appartato con lei, era stato visto ricevere il denaro. Da quell&#8217;episodio sono partite ulteriori indagini che hanno portato alla scoperta della situazione drammatica vissuta dalle due donne e alla denuncia. Madre e figlia da febbraio a ottobre dello scorso anno non uscivano pi\u00f9 di casa. Non potevano telefonare e gli era preclusa anche la possibilit\u00e0 di essere curate malgrado la donna, di 54 anni, sia diabetica e con seri problemi ad un occhio e la figlia soffra di problemi psichici molto seri. Addirittura Idone, che era geloso della ragazza, prima di allontanarsi dall&#8217;abitazione aveva ingannato le due donne facendo loro credere che la casa era piena di microspie e che non bisognava accendere il televisore perch\u00e9 attraverso quel mezzo venivano controllate.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Il Comandante Grimaldi: &#8220;Siamo riusciti a troncare una situazione gravissima che andava avanti da mesi&#8221; <\/strong><\/p>\n<p>Massimo Idone, lavorava come idraulico ed aveva precedenti penali di lieve entit\u00e0. L&#8217;uomo residente nel quartiere Archi, aveva ridotto le due donne, madre e figlia all&#8217;indigenza pi\u00f9 assoluta. Il comandante della Compagnia di Reggio Calabria, maggiore Pantaleone Grimaldi ha spiegato la situazione delle due donne, sole, che erano finite nelle mani di un uomo senza scrupoli che le aveva assoggettate psicologicamente, sottraendo loro ogni mese la pensione con cui vivevano. &#8220;Rimaste senza disponibilit\u00e0 finanziaria &#8211; ha aggiunto Grimaldi &#8211; e senza possibilit\u00e0 di acquistare cibo e farmaci poich\u00e9 entrambe soffrivano di gravi patologie, siamo riusciti a porre fine, grazie ad una segnalazione, alla loro schiavit\u00f9&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Aveva ridotto due donne in schiavit\u00f9 e alla fame.<\/p>\n","protected":false},"author":19,"featured_media":32272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32271"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32272"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}