{"id":32335,"date":"2014-04-20T04:13:34","date_gmt":"2014-04-20T02:13:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/pasqua-dolci-e-tradizioni-gustose-made-in-calabria\/"},"modified":"2023-01-17T12:52:21","modified_gmt":"2023-01-17T11:52:21","slug":"13842-pasqua-dolci-e-tradizioni-gustose-made-in-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13842-pasqua-dolci-e-tradizioni-gustose-made-in-calabria\/","title":{"rendered":"Pasqua, dolci e tradizioni gustose &#8216;made in Calabria&#8217;"},"content":{"rendered":"<p>CATANZARO &#8211; La cuzzupa, resta la regina incontrastata delle leccornie calabresi tipiche delle festivit\u00e0 pasquali.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Dal Pollino allo Stretto i dolci della Settimana Santa costituiscono, in Calabria, l&#8217;eredit\u00e0 di tradizioni millenarie che si rinnovano come per incanto nella Settimana Santa. Regina incontrastata, nelle tavole imbandite per la festa della Resurrezione, tanto in famiglia quanto anche nei locali pubblici, rimane la &#8220;cuzzupa&#8221;, altrimenti detta &#8220;guta&#8221;, &#8220;cuddhuraci&#8221;, o &#8220;cuculi&#8221; a seconda della dislocazione geografica. Preparata con un certo anticipo la &#8220;cuzzupa&#8221; pu\u00f2 assumere varie forme (del genere gallina, pesce, cuore o altro) a discrezione di chi la prepara con farina, lievito, olio extravergine di oliva, latte intero, scorza di limone, zucchero e uova. Come amuleto porta fortuna, al centro del biscotto, viene collocato un uovo sodo, ma anche pi\u00f9 di uno a discrezione. In passato il dolce veniva preparato anche dalle suocere e regalato per le feste pasquali alle neo spose come augurio di fertilit\u00e0. Altra golosit\u00e0, tipica del periodo, sono le nepitelle, dolci profumati a forma di mezzaluna fatti con noci, marmellata, mandorle, uva sultanina, fichi, cioccolato e cannella. Resta immutato, soprattutto in ragione dell&#8217;influenza esercitata dal fu Regno di Napoli, anche il fascino della pastiera a base di ricotta, germe di grano (o, secondo una nuova variante di sicuro successo, riso) ed essenza d&#8217;arancia. E dopo la Pasqua, tavole imbandite e dolci a volont\u00e0 anche per il luned\u00ec dell&#8217;Angelo, da vivere tra i boschi, nelle localit\u00e0 del litorale o negli agriturismi e ristoranti sempre, per\u00f2, all&#8217;insegna del buon cibo &#8220;made in Calabria&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; La cuzzupa, resta la regina incontrastata delle leccornie calabresi tipiche delle festivit\u00e0 pasquali.<\/p>\n","protected":false},"author":22,"featured_media":32336,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32335"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32336"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}