{"id":32339,"date":"2014-04-19T07:58:35","date_gmt":"2014-04-19T05:58:35","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/l-acqua-e-troppo-cara-il-sindaco-diffida-la-societa-soarko\/"},"modified":"2023-01-17T12:52:21","modified_gmt":"2023-01-17T11:52:21","slug":"13844-l-acqua-e-troppo-cara-il-sindaco-diffida-la-societa-soarko","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/13844-l-acqua-e-troppo-cara-il-sindaco-diffida-la-societa-soarko\/","title":{"rendered":"L&#8217;acqua \u00e8 troppo cara, il sindaco diffida la societ\u00e0 Soarko"},"content":{"rendered":"<p>COTRONEI (KR) &#8211; Il sindaco di Cotronei intende non accettare pi\u00f9 le tariffe stratosferiche imposte dalla societ\u00e0 ai cittadini.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Nicola Belcastro ha cos\u00ec provveduto a diffidare la Soarko dall&#8217;aumento dei prezzi per la gestione del sistema idrico licenziandola formalmente dal proprio mandato. L&#8217;obiettivo del sindaco \u00e8 ora quello di municipalizzare l&#8217;acqua. La rescissione del contratto annunciata da Belcastro \u00e8 stata giustificata con l&#8217;inadeguatezza dei servizi erogati e le lacune ed omissioni nei rapporti con la pubblica amministrazione. Una dura presa di posizione del Comune di Cotronei scattata al&#8217;imdomani di un annunciato aumento tariffario dei prezzi imposti da Soarko. Il primo cittadino ha espresso in una missiva al vetriolo indirizzata alla societ\u00e0 privata \u201ctotale contrariet\u00e0 all\u2019intenzione di aumentare le tariffe anche in virt\u00f9 del fatto che <strong>non sono stati portati a conoscenza dell\u2019Ente i dati del bilancio di Soakro, n\u00e9 le ragioni di tale richiesta di aumento delle tariffe, atteso che nessun piano industriale \u00e8 stato assunto dai soci<\/strong> e dalle amministrazioni, che hanno una funzione controllo della gestione\u201d. Controlli che la stessa Soarko avrebbe impedito non comunicando le informazioni richieste dagli organi competenti. Inoltre, Belcastro punta il dito contro la Soarko tacciandola di offrire &#8220;un servizio che non ha uno standard qualitativo sufficiente, come si pu\u00f2 rilevare dalle numerose e giornaliere sollecitazioni dei cittadini, che lamentano significativi disservizi\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COTRONEI (KR) &#8211; Il sindaco di Cotronei intende non accettare pi\u00f9 le tariffe stratosferiche imposte dalla societ\u00e0 ai cittadini.<\/p>\n","protected":false},"author":18,"featured_media":32340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-32339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=32339"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/32339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/32340"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=32339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=32339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=32339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}